{"id":2303233,"date":"2024-11-30T00:05:22","date_gmt":"2024-11-29T23:05:22","guid":{"rendered":"https:\/\/puntocritico.com\/ausajpuntocritico\/?p=2303233"},"modified":"2024-11-29T19:46:45","modified_gmt":"2024-11-29T18:46:45","slug":"el-fuego-y-la-palabra-elmer-gantry-pelicula-de-richard-brooks-1-960","status":"publish","type":"post","link":"https:\/\/puntocritico.com\/ausajpuntocritico\/2024\/11\/30\/el-fuego-y-la-palabra-elmer-gantry-pelicula-de-richard-brooks-1-960\/","title":{"rendered":"EL FUEGO Y LA PALABRA (\u00abElmer Gantry\u00bb). Pel\u00edcula de Richard Brooks (1.960)"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #008000; font-size: 14pt;\">EL FUEGO Y LA PALABRA (\u00abElmer Gantry\u00bb)<\/span><\/p>\n\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303573\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-frances-221x300.jpg\" alt=\"\" width=\"280\" height=\"379\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-frances-221x300.jpg 221w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-frances-756x1024.jpg 756w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-frances-768x1040.jpg 768w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-frances.jpg 945w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/p>\n<blockquote>\n<h2 id=\"main-title\" style=\"text-align: center;\"><span style=\"font-size: 24pt;\">El fuego y la palabra<\/span><\/h2>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 14pt;\">\u2018El fuego y la palabra\u2019 (Elmer Gantry, 1960), de Richard Brooks, es una corrosiva, y exultante, obra que pone en cuesti\u00f3n la condici\u00f3n esc\u00e9nica de las religiones, a trav\u00e9s de la hip\u00e9rbole de las escenificaciones religiosas, entre la convicci\u00f3n y la farsa, de las iglesias ambulantes, en carpas, ejemplificadas en el fundamentalismo evangelista a finales de los a\u00f1os 20.<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Por\u00a0Alexander Z\u00e1rate<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><a href=\"https:\/\/www.lasnuevemusas.com\/fuego-la-palabra\/?srsltid=AfmBOopSJdoFqbwOQuvtylEZjaSo-3F-WLOT-nKl4zrz2UCUi_wbo03Q\" target=\"_blank\" rel=\"noopener\">Las nueve musas<\/a><\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303566\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer_seduces-300x193.jpg\" alt=\"EL FUEGO Y LA PALABRA\" width=\"480\" height=\"309\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer_seduces-300x193.jpg 300w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer_seduces.jpg 668w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Brooks<\/strong> quer\u00eda llevar a cabo ya desde 1945 la adaptaci\u00f3n de la novela escrita por\u00a0<strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Sinclair_Lewis\" target=\"_blank\" rel=\"noopener noreferrer\">Sinclair Lewis<\/a><\/strong>\u00a0en 1927. De hecho, se lo hab\u00eda ya comentado al escritor, premio nobel de literatura en 1930, quien le apoy\u00f3 cuando public\u00f3 su primera novela, \u2018<em><strong>The brick foxhole<\/strong><\/em>\u2019 (1945), que ser\u00eda adaptada al cine en 1947, \u2018<strong><em>Encrucijada de odios<\/em><\/strong>\u2019, de <strong>Edward Dmytryk<\/strong>, con el cambio de la condici\u00f3n de la v\u00edctima: <strong>en la novela era asesinado por ser homosexual, en la pel\u00edcula por ser jud\u00edo<\/strong> (<em>por a\u00fan ser tab\u00fa la homosexualidad<\/em>).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El apoyo de <strong>Lewis<\/strong> fue doble. Elogi\u00f3 la novela en su cr\u00edtica en el \u2018<em>Esquire<\/em>\u2019. Y fue uno de los intelectuales que firm\u00f3 para interceder a favor de <strong>Brooks<\/strong> cuando fue amenazado por las instancias militares con ser llevado ante un tribunal castrense por el hecho de haber publicado la obra sin su aprobaci\u00f3n de los superiores, como exig\u00eda el reglamento. Cuando <strong>Brooks<\/strong> comparti\u00f3 su inter\u00e9s en adaptar su novela, <strong>Lewis<\/strong> le indic\u00f3 que pod\u00eda modificarla todo lo que quisiera, e incluso que leyera los cuestionamientos que recibi\u00f3 cuando fue publicada, aunque fuera un gran \u00e9xito de ventas, para as\u00ed mejorar su versi\u00f3n cinematogr\u00e1fica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Pero pocas productoras parec\u00edan dispuestas a financiar tal proyecto por su controversia y la\u00a0<strong>acidez sacr\u00edlega<\/strong> de su discurso. Fue decisiva la intervenci\u00f3n de <strong>Lancaster<\/strong> para conseguir que \u2018<em>despegara<\/em>\u2019, creando una productora conjunta, con la que encontraron el apoyo de <em>United<\/em> <em>Artists<\/em>. <strong>Brooks<\/strong> ya le hab\u00eda comentado durante el rodaje de \u2018<strong><em>Fuerza bruta<\/em><\/strong>\u2019 (1947), de <strong>Jules Dassin<\/strong>, de la que <strong>Brooks<\/strong> era guionista, su prop\u00f3sito de llevar a la pantalla esta obra. <strong>Lancaster<\/strong> se involucr\u00f3 plenamente. Particip\u00f3 de modo activo en la reelaboraci\u00f3n del gui\u00f3n, durante siete meses. Influy\u00f3 en la reducci\u00f3n de su extensi\u00f3n, sugiriendo que se suprimieran los pasajes relacionados con su juventud (l<em>a adaptaci\u00f3n acab\u00f3 centr\u00e1ndose en 76 de las 432 p\u00e1ginas totales de la novela<\/em>). As\u00ed como en la redefinici\u00f3n de su personaje,\u00a0 no un s\u00f3lo un arribista y\u00a0 farsante, sino dot\u00e1ndole de m\u00e1s contradicciones y matices. Aparte, para superar los c\u00f3digos de censura, <strong>Brooks<\/strong> elimin\u00f3 la condici\u00f3n de ministro de la iglesia de <em><strong>Gantry<\/strong><\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>El trayecto dram\u00e1tico se construye o trama sobre el contraste entre tres personajes, o actitudes<\/strong>: la convicci\u00f3n de aquella que cree, y es centro, y modelo referencial, de esa\u00a0<strong>representaci\u00f3n religiosa<\/strong>, la <strong><em>hermana Sharon<\/em><\/strong> (<strong>Jean Simmons<\/strong>). La convicci\u00f3n de aquel que no cree, el ateo, el esc\u00e9ptico, cr\u00edtico periodista de mentalidad progresista, <em><strong>Lefferts<\/strong><\/em> (<strong>Arthur Kennedy<\/strong>). Y la convicci\u00f3n del embaucador, del actor que domina esa escenificaci\u00f3n, como farsa, aunque no deje de creer pese a que no siga muy \u2018<em>religiosamente<\/em>\u2019 lo que predica, <strong><em>Elmer Gantry<\/em><\/strong> (<strong>Burt Lancaster<\/strong>). Este, centro neur\u00e1lgico de la obra, <em><strong>es un personaje tan contradictorio como parad\u00f3jico, un p\u00edcaro cautivador y un farsante con ciertos anhelos de notoriedad<\/strong><\/em>.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Ya en el pr\u00f3logo nos es presentado admirablemente con el relieve de los matices. Primero, fascinando, como puro \u2018<em>entertainer<\/em>\u2019, y engatusando, con su elocuente\u00a0 y desenvuelto dominio del verbo, a los asistentes en un bar. Segundo, tras una noche de intensa borrachera, y despertar junto a una mujer que en esa secuencia hab\u00eda \u2018<em>embelasado<\/em>\u2019, conversa con su madre por tel\u00e9fono, lamentando el que no pueda de nuevo visitarla. Sus gestos ya no son los mismos. La gestualidad exuberante y exagerada cuando \u2018<em>act\u00faa<\/em>\u2019 ante los dem\u00e1s deja traslucir otras emociones, m\u00e1s aut\u00e9nticas (<em>que le dotan de vulnerabilidad<\/em>), que a lo largo de la pel\u00edcula siempre estar\u00e1n sugeridas, frente a la explicitud desbordante de sus representaciones farsescas, a trav\u00e9s de las expresiones y acciones de <em><strong>Gantry<\/strong><\/em>, en soledad, o cuando deja entrever tras la m\u00e1scara emociones m\u00e1s fr\u00e1giles (<em>como el hast\u00edo y la vacuidad de su vida como comercial, en su primera conversaci\u00f3n con la hermana Sharon<\/em>).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La <em><strong>hermana Sharon<\/strong><\/em> representa lo que \u00e9l quisiera representar, significar, y c\u00f3mo quisiera sentirse. Se advierte una fuerte atracci\u00f3n que es a la vez admiraci\u00f3n (<em>probablemente ve en ella lo que le falta a \u00e9l, figura errante en una vida sin grandeza en la que se dedica a\u00a0<strong>vender sue\u00f1os<\/strong>, como comercial de ciudad en ciudad, pero que s\u00f3lo es enga\u00f1o<\/em>). A la vez, representa una oportunidad de poder alcanzar, al conseguir ser parte integrante, y protagonista como predicador, de ese circo ambulante religioso, esa notoriedad o sentimiento de grandeza que anhela.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El periodista, <em><strong>Lefferts<\/strong><\/em>, es una combinaci\u00f3n de varios personajes de la novela, no s\u00f3lo el que lleva su nombre (<em>compa\u00f1ero de seminario de <strong>Gantry<\/strong> y luego abogado, se fusiona con otros dos personajes, un reportero cr\u00edtico y un personaje agn\u00f3stico<\/em>). Representa la voz dentro del relato del liberal <strong>Brooks<\/strong>, un periodista de una estirpe casi m\u00edtica (<em>por excepcional<\/em>) como la que representaba el personaje de\u00a0<strong>Bogart<\/strong>\u00a0en una obra precedente, \u2018<strong><em>El cuarto poder<\/em><\/strong>\u2019 (<strong>1952<\/strong>): el periodista que busca ante todo la verdad y no el titular m\u00e1s espectacular que propicie las ventas (<em>de ah\u00ed que rechace escribir cierta noticia, porque no cree que posea la suficiente credibilidad, aunque implicar\u00eda un espectacular titular de primera p\u00e1gina<\/em>). Por a\u00f1adidura, se crea una singular, y hermosa, relaci\u00f3n de amistad con <strong><em>Gantry<\/em><\/strong>, aunque ambos tengan actitudes tan disimiles, incluso\u00a0 tras que <strong><em>Lefferts<\/em><\/strong>, que ha seguido los viajes de ese circo religioso, escriba un demoledor art\u00edculo sobre su condici\u00f3n farsesca, cuestionando sus inconsistencias.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong>RICHARD BROOKS<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">De todos modos, <em><strong>Sharon<\/strong><\/em> nos es presentada como alguien que cree en lo que hace, alguien con una capacidad de entrega verdadera, que no pretende enga\u00f1ar a nadie, lo que amplifica los matices y complejidad de la pel\u00edcula (<em>cualidad que inspira incluso la atracci\u00f3n y sentimiento de <strong>Gantry<\/strong>, como si pudiera ser como ella am\u00e1ndola<\/em>). En cambio, <strong>Brooks<\/strong> lanza \u00e1cidas invectivas contra la doblez o hipocres\u00eda, como el personaje de <em><strong>Babbit<\/strong><\/em> (<strong>Edward Andrews<\/strong>), que centrar\u00eda una de las grandes novelas de <strong>Lewis<\/strong>, \u2018<strong><em>Babbit<\/em><\/strong>\u2019 (<strong>1922<\/strong>). <em><strong>Babbit<\/strong><\/em>\u00a0 ve en el \u00e9xito de la <em><strong>hermana Sharon<\/strong><\/em> una forma de ascender en los poderes f\u00e1cticos de la ciudad (<em>cuando adem\u00e1s, sus acciones, clandestinas, poco tienen que ver con lo que predica<\/em>).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Tambi\u00e9n <strong>Brooks<\/strong> pone en cuesti\u00f3n la\u00a0<strong>zafia incultura<\/strong>\u00a0de <strong>los que se dejan embaucar o sugestionar<\/strong>, lo que implica una vitri\u00f3lica consideraci\u00f3n de la ignorancia que define a los habitantes tanto de los pueblos como de las ciudades. O c\u00f3mo son f\u00e1cilmente sugestionables, y a la vez qu\u00e9 volubles (<em>c\u00f3mo pasan de un extremo a otro, de la adoraci\u00f3n al rechazo<\/em>). A este respecto, se arremete contra esos estigmas y anatemas que genera la cuesti\u00f3n de el \u2018<em>buen nombre<\/em>\u2019, o \u2018<em>valor de imagen<\/em>\u2019, y que <em><strong>Gantry<\/strong><\/em> sufrir\u00e1 en sus carnes cuando su imagen se vea deteriorada por un frustrado intento de chantaje que se convertir\u00e1 en despechado escarnio p\u00fablico a trav\u00e9s de la prensa. El mismo final ejemplifica la falta de maniqueismo de la obra, y m\u00e1s bien c\u00f3mo alienta los interrogantes y los matices: se combinan un posible milagro con un fortuito accidente que determina una tragedia. Y como poso la puerilidad, o inmadurez, inherente en las mentes de los ac\u00f3litos (<em>como si el ni\u00f1o no creciera, o no madurara, como apunta con iron\u00eda <strong>Gantry<\/strong><\/em>).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Las frases finales que se intercambian <em><strong>Lefferts<\/strong><\/em> y <strong><em>Gantry<\/em><\/strong>, en las que se conjugan el sarcasmo con la complicidad, son memorables (<em>las cu\u00e1les se intentaron censurar; de hecho, hay copias sin estas frases<\/em>): <em><strong>Lefferts<\/strong><\/em> le dice a <em><strong>Gantry<\/strong><\/em>, \u2018<em>Te ver\u00e9 por ah\u00ed, hermano<\/em>\u2019, a lo que el segundo replica, \u2018<em>Te ver\u00e9 en el infierno, hermano<\/em>\u2019.<\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303572\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmergantryA0-300x217.jpg\" alt=\"\" width=\"440\" height=\"318\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmergantryA0-300x217.jpg 300w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmergantryA0.jpg 568w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #008000; font-size: 18pt;\">*******<\/span><\/strong><\/p>\n<h2 style=\"text-align: center;\"><span style=\"font-size: 24pt;\">EL FUEGO Y LA PALABRA (\u00abElmer Gantry\u00bb), Pel\u00edcula de Richard Brooks (1.960)<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/mega.nz\/embed\/TA1DQRYT#HyuQ1ealrwsS_eMkUflA6eeiQROHoAyUW_pKC4MA_vo\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">Elmer Gantre es una novela escrita por <a href=\"https:\/\/es.wikipedia.org\/wiki\/Sinclair_Lewis\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\">Sinclair Lewis<\/a> en el a\u00f1o 1926. La obra fue publicada en 1927 y Lewis se la dedic\u00f3 al periodista H. L. Mencken. Posiblemente el mejor estudio sobre la hipocres\u00eda desde Voltaire. Narra la historia de un evangelista de f\u00e1cil palabra que vive una vida de hipocres\u00eda y sensualidad, y cuya auto-indulgencia es tambi\u00e9n la cr\u00f3nica del reinado de la vulgaridad, que si no fuera por Lewis, no habr\u00eda dejado ning\u00fan registro de s\u00ed mismo.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">Novela escrita por Sinclair y publicada en 1927 en la cual hace una fuerte cr\u00edtica a todas las religiones y a sus representantes terrenales, su novela no ha \u00abenvejecido\u00bb ya que en los momentos actuales tiene una gran vigencia ante tantos funcionarios eclesi\u00e1sticos corruptos y de su car\u00e1cter eminentemente mercantilista y ni que decir de los sacerdotes pederastas. El autor nos devela que todos los centros de adoraci\u00f3n son simplemente un negocio. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">En el a\u00f1o 1960 fue estrenada la pel\u00edcula El fuego y la palabra (en Espa\u00f1a); Ni bendito ni maldito (en Chile) basada en la obra de Sinclair, la misma fue dirigida por Richard Brooks y con Burt Lancaster en el papel de Elmer Gantry. Siendo dif\u00edcil que alguien financiara la pel\u00edcula por su tem\u00e1tica Brooks y Lancaster fundaron una empresa independiente para elaborar el film. <\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt;\">Aunque hay un gran cumulo de modificaciones de la pel\u00edcula con respecto a la novela esta conserva el esp\u00edritu lewisiano. El film fue un \u00e9xito y gano cantidad de premios:<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.lecturalia.com\/libro\/14786\/elmer-gantry\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 14pt;\">Mathius<\/span><\/a><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2303561\" aria-describedby=\"caption-attachment-2303561\" style=\"width: 220px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/es.wikipedia.org\/wiki\/Sinclair_Lewis\" target=\"_blank\" rel=\"noopener\" data-schema-attribute=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2303561\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/Sinclair_Lewis_by_Oscar_Whiite_Pach_Brothers_Studio_c._1945_gelatin_silver_print_from_the_National_Portrait_Gallery_-_NPG-NPG_93_388_23_cropped-230x300.jpg\" alt=\"\" width=\"220\" height=\"287\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/Sinclair_Lewis_by_Oscar_Whiite_Pach_Brothers_Studio_c._1945_gelatin_silver_print_from_the_National_Portrait_Gallery_-_NPG-NPG_93_388_23_cropped-230x300.jpg 230w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/Sinclair_Lewis_by_Oscar_Whiite_Pach_Brothers_Studio_c._1945_gelatin_silver_print_from_the_National_Portrait_Gallery_-_NPG-NPG_93_388_23_cropped.jpg 330w\" sizes=\"auto, (max-width: 220px) 100vw, 220px\" \/><\/a><figcaption id=\"caption-attachment-2303561\" class=\"wp-caption-text\"><span style=\"color: #008000;\">Sinclair Lewis (fotograf\u00eda de Oscar Whiite). Fue el primer escritor estadounidense en obtener el Premio Nobel de Literatura (1930)<\/span><\/figcaption><\/figure>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><span style=\"color: #008000;\">*******<\/span><\/strong><\/span><\/p>\n<blockquote>\n<h3 id=\"main-title\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Ficha T\u00e9cnica:\u00a0<\/span><span style=\"font-size: 18pt;\">El Fuego y la Palabra, de Richard Brooks<\/span><\/h3>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 14pt;\"><em>(Elmer Gantry)<\/em>; 1960<\/span><\/strong><\/p>\n<div class=\"post-header-line-1\" style=\"text-align: justify;\"><span class=\"post-author vcard\" style=\"font-size: 14pt;\">Por <span class=\"fn\">Llu\u00eds Salvador<\/span><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><a href=\"https:\/\/lecturaserrantes.blogspot.com\/2010\/02\/el-fuego-y-la-palabra-de-richard-brooks.html\" target=\"_blank\" rel=\"noopener\">Lecturas errantes<\/a> 2010<\/span><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303575\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-apaisado-1-300x234.jpg\" alt=\"\" width=\"400\" height=\"312\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-apaisado-1-300x234.jpg 300w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-apaisado-1-768x598.jpg 768w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-apaisado-1.jpg 960w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Director<\/strong>: Richard Brooks<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Gui\u00f3n<\/strong>:\u00a0Richard Brooks,\u00a0<strong>basado en la novela\u00a0<\/strong>de <em>Sinclair Lewis.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Int\u00e9rpretes<\/strong>:\u00a0Burt Lancaster\u00a0(<em><strong>Elmer Gantry<\/strong><\/em>), Jean Simmons (<strong><em>Hermana Sharon Falconer, nacida Katie Jones<\/em><\/strong>), Arthur Kennedy (<strong><em>Jim Lefferts<\/em><\/strong>),\u00a0<em>Shirley Jones<\/em>\u00a0(<strong><em>Lulu Bains<\/em><\/strong>), Dean Jagger (<em><strong>William L. Morgan<\/strong><\/em>), Edward Andrews (<strong><em>George F. Babbitt<\/em><\/strong>), Patti Page (<em>Hermana Rachel<\/em>), John McIntire (<strong><em>Rev. John Pengilly<\/em><\/strong>).\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Dir. de fotograf\u00eda<\/strong>:\u00a0<em>John Alton.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>M\u00fasica<\/strong>: Andr\u00e9 Previn.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Dir. Art\u00edstica<\/strong>:\u00a0<em>Edward Carrere<\/em>.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Se pueden decir muchas cosas sobre la sociedad norteamericana, pero no se puede negar que dentro de todas sus contradicciones, las industrias culturales gozan de una admirable libertad para expresar sus opiniones. Tal vez no existe pa\u00eds en el mundo que tenga tanto respeto por la libertad religiosa (<em>no del todo, de acuerdo; habr\u00eda mucho que decir sobre las religiones no cristianas y sobre el ate\u00edsmo. Pero perm\u00edtanme esta leve simplificaci\u00f3n hoy<\/em>); pero dentro de este clima liberal en cuestiones de fe, la cinematograf\u00eda no ha tenido empacho en denunciar a los estafadores religiosos y otros chanchullos del mismo estilo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En este caso <strong>se trata de denunciar los enga\u00f1os de Elmer Gantry, un evangelista de los a\u00f1os veinte (<em>invenci\u00f3n del novelista Sinclair Lewis, pero s\u00edmbolo y arquetipo de la mir\u00edada de estafadores que proliferan y pululan por la sociedad americana<\/em>)<\/strong>. Por supuesto, al estilo Hollywood, es decir, incorporando un melodrama al argumento. Pero as\u00ed hacen las cosa y, reconozc\u00e1moslo, muchas veces lo hacen muy bien.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es m\u00e9rito del director\/guionista que esta pel\u00edcula interese tanto como lo hace, con un equilibro logrado entre la tensi\u00f3n dram\u00e1tica y la denuncia de la comercializaci\u00f3n religiosa, entre el argumento, la narrativa, y la fe y sus trampas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Efecto al que contribuyen e incrementan unas magn\u00edficas interpretaciones por parte de Burt Lancaster y Shirley Jones, por encima de la media, y del resto del cuerpo actoral encabezado por Jean Simmons.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Una pel\u00edcula sin fecha de caducidad, disfrutable hoy tanto como hace cincuenta a\u00f1os.<\/span><\/p>\n<p>&nbsp;<\/p>\n<\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303234 size-mh-magazine-content\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer_gantry-294553947-mmed-295x381.jpg\" alt=\"\" width=\"295\" height=\"381\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><span style=\"color: #008000;\">*******<\/span><\/strong><\/span><\/p>\n<h2 style=\"text-align: center;\" align=\"center\"><span style=\"font-size: 24.0pt; line-height: 107%;\">ELMER\u00a0GANTRY, UN PASTOR DE ALMAS DESCARRIADO A NO\u00a0IMITAR<\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><a href=\"https:\/\/lalinternaazul2.wordpress.com\/2024\/06\/15\/elmer-gantry-un-pastor-de-almas-descarriado-a-no-imitar\/\" target=\"_blank\" rel=\"noopener\">La linterna azul<\/a>,\u00a014\/06\/2024<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Por Orlando Solano B\u00e1rcenas<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303565\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/Elmer-Gantry-speech.jpg\" alt=\"\" width=\"440\" height=\"309\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\"><strong>Sinclair Lewis<\/strong> (1885-1951) gan\u00f3 el primer premio Nobel de literatura para Estados Unidos en 1930. En 1960 <strong>Richard<\/strong> <strong>Brooks<\/strong> film\u00f3 la pel\u00edcula\u00a0Elmer\u00a0Gantry, ganadora de varios premios de\u00a0las\u00a0academias especializadas en el S\u00e9ptimo Arte. En ambas obras se analiza un fen\u00f3meno de actualidad universal:\u00a0Las\u00a0iglesias y los pastores protestantes, de diferentes confesiones del cristianismo. Ambos abundantes y de diferentes matices, calidades y realizaciones. De todo hay en la Vi\u00f1a del Se\u00f1or, es bien sabido. Analizaremos la novela y la pel\u00edcula en este ensayo, bajo esta pregunta: \u00bfHicieron Lewis y Brooks una profec\u00eda de lo que pasar\u00eda m\u00e1s tarde con los fen\u00f3menos de sectas y pastores m\u00e1s dados a lo terrenal que a lo espiritual? S\u00ed, como lo demuestra el arrollador avance de algunas de estas deformaciones en Colombia, Am\u00e9rica Latina y pa\u00edses de los Tres Mundos del desarrollo socioecon\u00f3mico.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">El premio Nobel de Literatura<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es uno de los cinco que entrega cada a\u00f1o el Comit\u00e9 del Nobel, en consideraci\u00f3n a \u201cA quien hubiese producido en el campo de la literatura la obra m\u00e1s destacada, en la direcci\u00f3n ideal\u201d. En la d\u00e9cada de 1930, \u201cel mayor beneficio para la humanidad\u201d se interpret\u00f3 como de escritores \u201cal alcance de todos\u201d. Se le adjudic\u00f3 a Sinclair Lewis: \u201cPor su arte vigoroso, gr\u00e1fico y pl\u00e1stico en la descripci\u00f3n y habilidad en la construcci\u00f3n \u2014con ingenio y humor\u2014 de nuevos tipos y caracteres de personajes\u201d. Sobre la novela\u00a0Elmer\u00a0Gantry, se dijo que es posiblemente el mejor estudio sobre la hipocres\u00eda desde Voltaire porque en su examen sat\u00edrico de la religi\u00f3n evang\u00e9lica, Lewis captura la creciente tensi\u00f3n cultural y pol\u00edtica durante la d\u00e9cada de 1920 entre\u00a0las\u00a0fuerzas del secularismo y el fundamentalismo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2303570\" aria-describedby=\"caption-attachment-2303570\" style=\"width: 440px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2303570\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/sinclair-lewis-300x191.jpg\" alt=\"\" width=\"440\" height=\"280\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/sinclair-lewis-300x191.jpg 300w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/sinclair-lewis-768x489.jpg 768w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/sinclair-lewis.jpg 960w\" sizes=\"auto, (max-width: 440px) 100vw, 440px\" \/><figcaption id=\"caption-attachment-2303570\" class=\"wp-caption-text\"><span style=\"color: #008000;\">Sinclair Lewis<\/span><\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Lewis, un rebelde y cr\u00edtico mordaz de la sociedad de EE.UU. de una \u00e9poca dif\u00edcil<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Increyente, practic\u00f3 la s\u00e1tira social sobre la religi\u00f3n, los hombres de negocio, la burgues\u00eda del Medio Oeste y los despose\u00eddos\u00a0en\u00a0las\u00a0novelas Calle Mayor,1920; Babbit, 1922 y\u00a0Elmer\u00a0Gantry, 1927. Egresado de Yale. Novelista, dramaturgo, periodista y escritor del movimiento del Realismo. Miembro de la Academia Estadounidense de\u00a0las\u00a0Artes y\u00a0las\u00a0Letras. Ganador de varios premios. Desde muy joven empez\u00f3 a redactar un diario. A los trece a\u00f1os se escap\u00f3 de su casa para intentar enrolarse como tambor en la Guerra hispano-estadounidense. Viaj\u00f3 a trav\u00e9s del pa\u00eds hasta 1915. Escribi\u00f3 poemas y relatos cortos con trabajos ocasionales como periodista y corrector de pruebas. En 1926 rechaz\u00f3 el Premio Pulitzer. John Ford film\u00f3 su novela Arrowsmith, 1925. Varias de sus obras han sido llevadas al teatro, la radio y la televisi\u00f3n.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En 1935 public\u00f3 la novela It Can\u2019t Happen Here donde describi\u00f3 a un dictador fascista que llega al poder democr\u00e1ticamente en los Estados Unidos, considerada por algunos como una profec\u00eda de la elecci\u00f3n de Donald Trump, el mes\u00edas de Am\u00e9rica again. Wells, su hijo, fue muerto por un francotirador alem\u00e1n durante la Segunda Guerra Mundial. Muri\u00f3 en Roma en 1951 por avanzado alcoholismo. Sus restos est\u00e1n en su ciudad natal (Sauk Center, Minnesota). Dej\u00f3 unas 22 obras literarias. Ha sido considerado la conciencia de su generaci\u00f3n durante la d\u00e9cada de 1920 y la Gran Depresi\u00f3n, junto a John Steinbeck y\u00a0las\u00a0historias del condado de Yoknapatawpha en\u00a0Las\u00a0uvas de la ira, 1939. El realismo social y pol\u00edtico de Lewis es feroz.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Sinclair Lewis un verdadero profeta<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En\u00a0Elmer\u00a0Gantry previ\u00f3 el avance de\u00a0las\u00a0religiones fundamentalistas que se ir\u00edan apropiando de\u00a0las\u00a0mentes de los provincianos de gran parte del pa\u00eds, lo que trajo grandes preocupaciones y controversias. En esta novela analiza\u00a0las\u00a0diferentes vertientes del evangelismo de Estados Unidos, la naci\u00f3n con mayor diversidad religiosa del mundo (1.500 cuerpos y sectas religiosas, unas 75 variedades de bautistas).\u00a0Las\u00a0cifras: Protestantismo (42%); Catolicismo (21%); Irreligi\u00f3n (18%); Agnosticismo (6%); Ate\u00edsmo (5%); Mormonismo (2%).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El Protestantismo est\u00e1 representado por\u00a0las\u00a0iglesias evang\u00e9licas del presbiterianismo\/calvinismo y el metodismo, identificadas con la Reforma Protestante (luteranos, anglicanos, bautistas, metodistas, adventistas, congregacioncitas, amish, menonitas, pentecostales y otras); grupos que basan la autoridad religiosa de forma exclusiva en la Biblia y no en lo apost\u00f3lico, como el catolicismo. Postulados b\u00e1sicos: \u201cSolo por medio de la Sagrada Escritura\u201d; \u201cSolo por la fe\u201d; \u201cSolo por la gracia\u201d; \u201cSolo a trav\u00e9s de Cristo\u201d y \u201cSolo para la gloria de Dios\u201d. El encuentro con Jes\u00fas, el Esp\u00edritu Santo y Dios es personal. No hay papado, ni culto a los santos ni a la Virgen Mar\u00eda. Son dados a los \u201cavivamientos\u201d, los carismas, la Teolog\u00eda de la prosperidad (que considera el \u00e9xito econ\u00f3mico y la vida cotidiana mundana como resultado de un v\u00ednculo \u201caqu\u00ed y ahora con Dios\u201d), a hablar en lenguas extra\u00f1as (Glosolalia), el boca a boca,\u00a0las\u00a0redes, los espacios televisivos o \u201ciglesia electr\u00f3nica\u201d de pastores showman, la cura de enfermedades, el sacerdocio y el pastoreo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Tanto en la novela (no sin sorna) como en la pel\u00edcula (con cierta simpat\u00eda de Brooks) aparecen mencionados muchos de estos grupos en su faccionalismo. Lewis profetiz\u00f3 el arrollador avance de casi todas estas tendencias y sectas: 360.000 iglesias, mezquitas y sinagogas protegidas por la completa separaci\u00f3n entre la Iglesia y el Estado requerida por la Primera Enmienda de la Constituci\u00f3n y la Cl\u00e1usula de Establecimiento y Libre Ejercicio, que la garantizan. Analicemos primero la novela y luego la pel\u00edcula. La vi \u2014estupefacto\u2014 en el a\u00f1o de su estreno. Todav\u00eda lo estoy.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">La novela\u00a0Elmer\u00a0Gantry, Harcourt Ed.1926, 427 p.<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Fue dedicada con admiraci\u00f3n al periodista y escritor sat\u00edrico H.L. Mencken. Es un icono de la cr\u00edtica social y el realismo literario. Luego de hablar Lewis con varios predicadores de Kansas City narr\u00f3 la historia de un joven atleta universitario, narcisista y mujeriego que abandona los estudios de derecho para asistir a un seminario bautista, donde es ordenado Ministro. Mujeriego y bebedor, es expulsado del seminario antes de completar su licenciatura, que se recicla durante algunos a\u00f1os como vendedor ambulante de equipos agr\u00edcolas (en la pel\u00edcula\u00a0Elmer\u00a0Gantry ser\u00e1 un vendedor de brilladoras y licuadoras el\u00e9ctricas).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Luego conoce a la popular pastora motivacional y evangelista de iglesias de carpas de circo, Sharon Falconer, con quien se involucra sentimentalmente y lograr\u00e1, gracias a su oratoria y teatralidad, aumentar la colecta de diezmos y la construcci\u00f3n de un templo de mamposter\u00eda a\u00a0orillas\u00a0del mar. Para este personaje femenino, Lewis se inspir\u00f3 en Aimee Semple McPherson, fundadora en 1927 del evangelismo radial pentecostal de la Iglesia Internacional Cuadrangular del Evangelio. La hermana Falconer morir\u00e1 en un inesperado incendio el d\u00eda de la consagraci\u00f3n del templo junto a varios fallecidos, en medio del \u00e9xtasis del fuego ella parece entregarse al martirologio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Elmer\u00a0sigue su vida en calidad breve de Evangelista del Nuevo Pensamiento. Finalmente se convierte en ministro metodista y se casa con una de sus feligresas, pero sigue en su vida de conquistas amorosas. A\u00f1os m\u00e1s tarde y gracias a su liderazgo religioso le conceden la congregaci\u00f3n m\u00e1s grande de la ciudad de Zenith, inventada por Lewis. Arranca una carrera veloz que le permite manipular la pol\u00edtica local, estatal y nacional. Para esto, organiza grupos de feligreses fan\u00e1ticos que organizan razzias contra bares, prost\u00edbulos y los clientes. Hambriento de poder y aferrado a la corrupci\u00f3n persigue a personas que no le siguen el juego, una de ellas es su antiguo amigo Frank Shallard, un ministro sincero y cercano a la increencia que no participa del prop\u00f3sito moral de la iglesia evang\u00e9lica. Shallard es casi linchado por un escuadr\u00f3n de incondicionales de Gantry, lo que no deja de recordar al KKK.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Elmer\u00a0hace figura de hip\u00f3crita en varios aspectos: predica el amor en sus sermones y es infiel, condena la ambici\u00f3n y es fundamentalmente ambicioso, vocifera en el p\u00falpito contra la lujuria y lo es en plenitud. Pero, un d\u00eda aparece una chica de su pasado de seductor que le monta un escenario de chantaje y denuncia de su vida desordenada. Ayudado por un amigo, un abogado poderoso y una agencia privada de detectives logra evitar su ca\u00edda. Anuncia que ha escarmentado y jura renunciar a su vida de pecado. Empero pocos d\u00edas despu\u00e9s durante un serm\u00f3n observa la belleza de una joven feligresa y\u2026<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El libro fue recibido con mucha pol\u00e9mica. Hizo furor en\u00a0las\u00a0huestes cercanas al laicismo y desat\u00f3 la furia de los creyentes de casi todas\u00a0las\u00a0iglesias y sectas del momento. Fue prohibido nada menos que en la culta Boston y en ciudades del Deep South. Los p\u00falpitos clamaron al cielo. Un alto cl\u00e9rigo sugiri\u00f3 que Lewis deb\u00eda ser encarcelado cinco a\u00f1os y le llam\u00f3 \u201cla cohorte de Satan\u00e1s\u201d. Otro cl\u00e9rigo lo \u00abinvit\u00f3\u00bb a una celda en la c\u00e1rcel de New Hampshire y a su linchamiento en Virginia. Tambi\u00e9n hubo amenazas contra su vida. En realidad el libro fue un \u00e9xito comercial, como la obra de ficci\u00f3n m\u00e1s vendida en Estados Unidos en 1927. Alg\u00fan cr\u00edtico dijo que el libro era solo una s\u00e1tira de la actividad religiosa de Estados Unidos. Sin embargo, H.G. Wells escribi\u00f3 que era una verdadera observaci\u00f3n v\u00e1lida de la cultura estadounidense.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La tem\u00e1tica de la novela gira sobre la cr\u00edtica social a la \u201ccomplacencia estadounidense\u201d con ciertas sectas religiosas que abusan de Dios y de los bolsillos de sus reba\u00f1os y a quienes les proponen el fuego eterno del infierno si se retiran de la secta o no diezman. En la obra, Falconer y Gantry ofrecen a sus seguidores \u2014el reba\u00f1o\u2014 un futuro mejor en otra vida, pero con avidez de personas dadas al negocio.\u00a0Elmer\u00a0inicia una serie de innovaciones t\u00e9cnicas propias del m\u00e1rquetin, el espect\u00e1culo y la radio donde lo religioso resultar\u00e1 siendo un gran circo de grandes, vivos y entusiastas espect\u00e1culos en los que el p\u00fablico participar\u00e1 activamente en el ruido del delirio religioso, del frenes\u00ed medi\u00e1tico del sensacionalismo, de v\u00edtores y abucheos de: \u00a1Gloria Gloria Aleluya!, con tal profusi\u00f3n que produce mareo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En la pel\u00edcula la hermana Falconer ser\u00e1 presentada como m\u00e1s espiritual y\u00a0Elmer\u00a0como menos ambicioso. Seducida Sharon por la labia de\u00a0Elmer, este tiene una moment\u00e1nea ca\u00edda por la venganza de Lul\u00fa Baines, la hija de un pastor a quien hab\u00eda igualmente seducido en el pasado. As\u00ed mismo, por obra de un periodista ateo y esc\u00e9ptico \u2014Jim Lefferts\u2014 que intuye en Gantry un embaucador. Luego de chantajes y arreglos econ\u00f3micos,\u00a0Elmer\u00a0logra salir adelante y recupera a Sharon, quien pronto morir\u00e1 por el fuego desatado incidentalmente en su templo ahora de mamposter\u00eda y no de toldas y carpas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Las\u00a0experiencias de reportero de Sinclair Lewis le ayudaron a captar una Norteam\u00e9rica profunda en sus acentos locales, costumbres, maneras de ser y los servicios sociales en una sociedad capitalista, todo en tono de s\u00e1tira hacia los pueblerinos, pero tambi\u00e9n a los intelectuales que los miraban por encima del hombro y con desprecio. Esta obra representa la gran novel\u00edstica sobre el \u201cprovincianismo estadounidense\u201d de\u00a0las\u00a0numerosas y agresivas entre s\u00ed sectas religiosas, los rotarios, el ideal del triunfo por el peque\u00f1o comercio, los clubes sociales de pueblo, en general sobre el conformismo generalizado de los hombres de negocios, m\u00e9dicos de mediana edad, optimistas y autocomplacientes, cuyos horizontes estaban limitados por los l\u00edmites de su aldea, como ya lo hab\u00eda hecho en Arrowsmith, 1925.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En la novela Lewis es militante anticristiano, progresista. En la pel\u00edcula \u2014donde es coguionista de Brooks\u2014 se ve un Gantry menos truculento, p\u00edcaro, ebrio, jugador o infiel, pero hasta agradable y digno de la redenci\u00f3n, no se sabe si por ser el director un creyente o por la necesidad de superar los c\u00f3digos de la censura.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Elmer\u00a0Gantry, es una novela que contin\u00faa la s\u00e1tira social de Lewis contra\u00a0las\u00a0capas bajas de la clase media, la anatom\u00eda social, la situaci\u00f3n de la mujer, la protesta social, el sistema social y econ\u00f3mico moderno, la pol\u00edtica, el poder, la peque\u00f1a corrupci\u00f3n, el consumismo, la publicidad la comedia negra de un mundo inhumano y brutal y sus efectos deprimentes, el mal gusto de la cultura de masas y la burla del patetismo del sue\u00f1o americano. Es una literatura de la desilusi\u00f3n existencial de la Lost Generation. Sinclair Lewis es un observador indignado (como su alter ego, Jim Lefferts). Su progresismo es relacionado con su segunda esposa \u2014Dorothy Thompson\u2014 periodista de avanzada, feminista, sufragista e hija de un pastor metodista.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Algunas frases punzantes en\u00a0Elmer\u00a0Gantry<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u00ab\u00c9l naci\u00f3 para ser senador. Nunca dijo nada importante, y siempre lo dijo sonoramente\u00bb.(I-1); \u00abDe hecho, lo hab\u00eda obtenido todo de la iglesia y de la escuela dominical, excepto, quiz\u00e1s, cualquier anhelo por la decencia, la bondad y la raz\u00f3n\u00bb.(II-1); \u00abFrank\u2026 hizo del templo de Salom\u00f3n no solo un objeto deprimente\u2026, sino un santuario real en el que moraba un dios activo y aterrador\u00bb. (VII-2); \u00ab\u00bfQu\u00e9 hab\u00eda aprendido?\u2026 La teor\u00eda de que India y \u00c1frica tienen problemas porque no est\u00e1n cristianizados, pero que Bangor y Des Moines cristianizados tienen problemas porque el diablo, un ser obviamente m\u00e1s poderoso que Dios omnipotente, se cuela para contrarrestar el trabajo de los predicadores bautistas\u2026 Y hab\u00eda aprendido que la pobreza es una bendici\u00f3n, pero que los banqueros son los mejores di\u00e1conos\u00bb. (XVII-1); \u00abEl Creador del universo con estrellas a cien mil a\u00f1os luz de distancia estaba interesado, furioso y muy personal acerca de si un ni\u00f1o peque\u00f1o jugaba b\u00e9isbol un domingo por la tarde\u00bb. (XVII-1);<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">\u00abTodav\u00eda no estaba del todo seguro de estar haciendo algo bueno, aparte de proporcionar la droga de la esperanza religiosa a la gente timorata temerosa del fuego del infierno y temerosa de caminar sola\u00bb. (XXIV-2); \u00abMe criaron para creer que el Dios cristiano no era un servidor p\u00fablico asustado y comprometido, sino el creador de toda la verdad despiadada, y creo que ese entrenamiento me ech\u00f3 a perder. \u00a1De hecho, tom\u00e9 en serio a mis maestros!\u00bb (XXVIII-1); \u201cUna escuela apropiada no deber\u00eda ense\u00f1ar nada m\u00e1s que tenedur\u00eda de libros, agricultura, geometr\u00eda, lenguas muertas hechas muertas al dejar de lado toda la literatura divertida, y la Biblia hebrea interpretada por hombres magn\u00edficamente entrenados para ignorar\u00a0las\u00a0contradicciones, hombres t\u00e9cnicamente llamados \u2018Fundamentalistas\u2019\u201d. (XXIX-9).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El libro\u00a0Elmer\u00a0Gantry: La religi\u00f3n industrializada en los Estados Unidos de Sinclair Lewis tr. de Carlos de On\u00eds Editorial Cenit, Madrid, 1935 se puede leer gratis en internet.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">La pel\u00edcula\u00a0Elmer\u00a0Gantry, 1960 ganadora del Oscar a la mejor pel\u00edcula<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Dirigida por Richard Brooks. Titulada en Espa\u00f1a El fuego y la palabra. 1960 fue un a\u00f1o de grandes pel\u00edculas. Destaca la obra maestra de Stanley Kramer Inherit the Wind (Heredar\u00e1s el viento). Corresponde a una \u00e9poca en que Hollywood estaba comenzando a analizar los peligros del fundamentalismo religioso, que sigue siendo poderoso en Estados Unidos hoy en d\u00eda. El guion del dueto Brooks-Lewis es una obra de gran teatralidad, el formato que quisieron darle.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Puede ser resumida as\u00ed: Un vendedor ambulante de hablar r\u00e1pido, encantador y locuaz (Burt Lancaster=\u00a0Elmer\u00a0Gantry, premio Oscar al mejor actor en 1960), convence a una evangelista sincera (Jean Simmons= Sharon Falconer) de que puede ser un predicador eficaz para su causa. Gan\u00f3 3 premios \u00d3scar, 11 premios y 14 nominaciones en total. Todav\u00eda ofrece una gran actualidad. Siendo dif\u00edcil que alguien financiara la pel\u00edcula por su tem\u00e1tica Brooks y Lancaster fundaron una empresa independiente para elaborar el film.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Aunque hay un gran cumulo de modificaciones de la pel\u00edcula con respecto a la novela esta conserva el esp\u00edritu cr\u00edtico de Lewis. Entonces, el realismo extremo de la novela es suavizado un poco o un mucho en la filmaci\u00f3n, lo que depende de la \u00f3ptica que se le aplique. Eran tiempos todav\u00eda del C\u00f3digo Censor y del Macartismo. El\u00a0Elmer\u00a0de Lancaster es un personaje m\u00e1s simp\u00e1tico y atractivo que el original del libro. Ya no es un ministro del culto, sino un culebrero vendedor de electrodom\u00e9sticos, siempre sin dinero y ebrio. Sus trucos de vendedor ambulante los pone al servicio de Dios o de la religi\u00f3n, para aumentar la colecta de diezmos para la pastora Sharon Falconer (quien no tiene estudios ni t\u00edtulos que mostrar en esta materia o profesi\u00f3n).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Durante un \u201cavivamiento\u201d ve a la pastora y queda prendado.\u00a0Elmer\u00a0llega a ella con cupidez, pero el amor lo ablanda un tanto y hasta espera que este sentimiento o ella lo rediman. Su ret\u00f3rica le permite dialogar con cierta solvencia frente al cr\u00edtico y \u00e1cido periodista Jim Lefferts (Arthur Kennedy); en realidad ambos parecen admirarse mutuamente y a ratos parecen amigos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Luego reaparece en su vida una hermosa prostituta hija de un diacono llamada Lulu Baines (Shirley Jones, premio Oscar a la Mejor actriz de Reparto) a quien hab\u00eda seducido y abandonado. Se inician los problemas para\u00a0Elmer, sometido por ella a chantaje por venganza mediante fotos en escenas de amor prohibido para un pastor de almas supuestamente ejemplar. La multitud de fieles lo insulta, escupe y llena de basuras. La carpa-templo es destruida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Sharon le perdona la infidelidad. Viene la gran inauguraci\u00f3n del templo de mamposter\u00eda construido con los diezmos aumentados por la labia de\u00a0Elmer, pero un fuego incidental lo quema. Sharon se abandona al fuego y muere.\u00a0Elmer\u00a0trata de salvarla pero no puede, porque la multitud no le dej\u00f3 llegar a su lado. Gantry recibe la oferta de seguir con la iglesia de Sharon, pero no acepta. Prefiere irse, sin saberse hacia d\u00f3nde. En la novela Lefferts le dice \u201cHasta la vista, hermano\u201d y Gantry le responde enf\u00e1ticamente \u201cHasta el infierno, hermano\u201d. Genio y figura. Pero, esto fue censurado en la pel\u00edcula porque mostrar\u00eda que no se habr\u00eda \u00abreformado\u00bb realmente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En el filme\u00a0Elmer\u00a0figura como un pecador algo arrepentido, sin que se den m\u00e1s detalles. Carencia que ha dado lugar a mucha controversia sobre si Brooks quiso hacer obra religiosa o esquivar la censura. El Gantry de la novela, parece ser condenado; el de la pel\u00edcula, parece redimido por Brooks (sin olvidar que Lewis particip\u00f3 en el guion).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La pel\u00edcula, como el libro, tambi\u00e9n pudo enviar un mensaje a ciertos predicadores evangelistas de conductas dudosas, muy dados al tele evangelismo, cadenas radiales, avivamientos, jornadas de sanaci\u00f3n, teolog\u00edas del evangelio de la prosperidad, universidades, parques tem\u00e1ticos, bandas de rock cristiano, aviones, lujos y ciertas investigaciones judiciales por inmoralidad sexual y fraudes y evasi\u00f3n de impuestos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Algunas pel\u00edculas hab\u00eda y han expuesto estos hechos y situaciones. Lo hizo Frank Capra con La mujer milagrosa, 1932; de Stanley Kramer Heredar\u00e1s el viento (sobre el Juicio del mono o Juicio de Scopes y\u00a0las\u00a0teor\u00edas de la evoluci\u00f3n de Charles Darwin); de Richard Pearce Salto de fe (Leap of Faith, 1992). A partir de La noche del cazador, 1955 de Charles Laughton se hicieron varias pel\u00edculas sobre el predicador tramposo o dudoso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Enfrentarse Brooks en 1960 a los \u201crevivalistas\u201d tambi\u00e9n fue un acto valiente. En efecto, muchos cines se negaron a mostrarla. Para algunos es prof\u00e9tica porque previ\u00f3 el fundamentalismo religioso moderno, como lo har\u00eda nuevamente en 1972 el documental de Marjoe, de Howard Smith y Sarah Kernochan, mucho m\u00e1s realista y relevante al versar sobre el hecho real de un ni\u00f1o evangelista que deviene en predicador ambicioso y corrupto.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">El Director Richard Brooks (1912-1992)<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Conductor de grandes pel\u00edculas como A sangre fr\u00eda (1967), La gata sobre el tejado de zinc (1958), Los profesionales,1966 y\u00a0Elmer\u00a0Gantry (1960). Casado posteriormente con Jean Simmons (Sharon Falconer), con\u00a0Elmer\u00a0Gantry demostr\u00f3 una gran capacidad narrativa y pericia para escoger un excelente elenco y camar\u00f3grafos expertos en cine negro; tambi\u00e9n en la selecci\u00f3n de la m\u00fasica de Andr\u00e9 Previn, ganadora del Oscar a la Mejor M\u00fasica. Es otra buena adaptaci\u00f3n de obras literarias conocidas al cine, un cl\u00e1sico. Novela prof\u00e9tica porque\u00a0Elmer\u00a0Gantry sigue vivo y m\u00e1s duro de matar que Bruce Willys, como ciertos pastores que campean en pa\u00edses de Am\u00e9rica Latina y de los Tres mundos\u2026<\/span><\/p>\n<h3 style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Burt Lancaster (1913-1994) es\u00a0Elmer\u00a0Gantry<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Jug\u00f3 el rol de su vida. Hay consenso, \u00e9l es el Gantry que grita:\u00a0\u201c \u00a1Pecado, pecado, pecado! \u00a1Todos ustedes son pecadores! \u00a1Est\u00e1is todos condenados a la perdici\u00f3n y se quemar\u00e1n en el infierno!\u201d Dif\u00edcil saber si Gantry es veraz o mentiroso.\u00a0Elmer\u00a0es todo fuego, azufre y miedo. Dientes brillantes, energ\u00eda atl\u00e9tica, carisma y cabello salvaje, utiliza su propia destreza f\u00edsica para una gran ventaja (hab\u00eda sido acr\u00f3bata de circo antes de ser actor). Lancaster interpreta al antih\u00e9roe como un p\u00edcaro de tal encanto que casi se llega a querer.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Una de\u00a0las\u00a0mejores actuaciones cinematogr\u00e1ficas de todos los tiempos. El Oscar le fue entregado porque es Gantry, un salvador de almas el domingo y un gran generador de dinero el lunes. De su actuaci\u00f3n dijo: \u201cEsta fue la mejor parte de mi vida, porque siempre prefer\u00ed interpretar un papel tan emocionante y vital como\u00a0Elmer\u00a0Gantry y no el de una docena de esos grandes y guapos h\u00e9roes que siempre consiguen a la chica hermosa\u201d. Super\u00f3 en el Oscar de ese a\u00f1o nada menos que a Spencer Tracy, Laurence Olivier, Trevor Howard y Jack Lemmon.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Jean Simmons (1929-2010) es Sharon Falconer<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En la pel\u00edcula la hermana Falconer es una verdadera creyente, no en la novela donde figura como una mujer ambiciosa de riquezas y presume de alcurnia. Inspirada en Aimee Semple McPherson, una evangelista episcopal, celebridad medi\u00e1tica muy influyente entre 1920-1930 y fundadora de la Iglesia Cuadrangular, seg\u00fan algunos comentaristas, de vida con episodios dudosos. Jean Simmons fue la elecci\u00f3n perfecta para este papel, al igual que Lancaster para el suyo. Como Sharon es dominante, espiritual, espeluznante y lujuriosa, por turnos. Una especie de Juana de Arco evang\u00e9lica. Una actuaci\u00f3n luminosa, toda fragilidad y sexualidad reprimida que mereci\u00f3 el tercer Oscar para la pel\u00edcula en opini\u00f3n de muchos.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Shirley Jones (1934- ) es Lul\u00fa Baines<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Recibi\u00f3 el Oscar a la Mejor Actriz de Reparto. Sorprendida por su padre en situaci\u00f3n embarazosa con\u00a0Elmer\u00a0narra a sus amigas del burdel, riendo alegremente mientras baila: \u00abOh, \u00e9l me dio instrucciones especiales en el p\u00falpito la v\u00edspera de Navidad. Lleg\u00f3 a aullar \u00a1Arrepi\u00e9ntete! \u00a1Arrepi\u00e9ntete! y yo me puse a gemir \u00a1S\u00e1lvame! \u00a1S\u00e1lvame! y lo primero que supe fue que me infundi\u00f3 el temor de Dios tan r\u00e1pido que nunca escuch\u00e9 los pasos de mi viejo\u00bb (armado). Parlamento divertido y magistral actuaci\u00f3n posterior al momento de seducir y chantajear a\u00a0Elmer, que al parecer le merecieron el Oscar.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Arthur Kennedy (1914-1990) es Jim Lefferts<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es el reportero de investigaci\u00f3n, quien \u2014desde su perspectiva\u2014 parece narrar la pel\u00edcula. Es la voz de la raz\u00f3n, de la verdadera compasi\u00f3n, de la verdad. Para algunos cr\u00edticos es de hecho la voz del propio Sinclair Lewis. Como Jean Simmons, tambi\u00e9n mereci\u00f3 un Oscar por encarnar al aut\u00e9ntico periodista esc\u00e9ptico, increyente, hombre de raz\u00f3n en medio del enorme ruido de\u00a0las\u00a0carpas de avivamiento. Afilando un l\u00e1piz con delectaci\u00f3n le dicta a su secretaria \u2014con gran actuaci\u00f3n actoral esta frase: \u00ab\u00bfEs una iglesia, es una religi\u00f3n o es un espect\u00e1culo de circo completo con monstruos, magia y chusma?\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">M\u00e1s adelante asume una posici\u00f3n cr\u00edtica cuando expresa en este parlamento: \u00abA\u00a0las\u00a0turbas no les gusta que sus dioses sean humanos\u00bb. Lefferts es un personaje basado en Henry Louis Mencken, otro esc\u00e9ptico, libertario, sat\u00edrico cr\u00edtico cultural y acad\u00e9mico \u2014como Sinclair Lewis\u2014 quien describi\u00f3 notablemente a los feligreses de los avivamientos de Tennessee. Entonces, si Jim Lefferts es Mencken, Sinclair Lewis es H.L. Mencken. Dado que la novela trata de\u00a0las\u00a0sectas religiosas, es el momento de estudiar qu\u00e9 son estas.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Las\u00a0sectas religiosas<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Una secta (del lat\u00edn sequi o \u201cseguir,\u201d y secare o \u201ccortar\u201d, \u201cseparar\u201d) es una organizaci\u00f3n, generalmente ideol\u00f3gica, cultural, pol\u00edtica o religiosa concreta que \u2014como una secci\u00f3n o sector se \u201caparta\u201d\u2014 separa, desgaja, desprende o se escinde de\u00a0las\u00a0doctrinas tradicionales u oficiales de un conjunto mucho m\u00e1s amplio (como una contracultura). Estrategia en la que suele adoptar un car\u00e1cter secreto para los que no pertenecen a ella como resultado de la divisi\u00f3n, generalmente encabezada por un l\u00edder que los arrastra y suelen ser narcisistas, carism\u00e1ticos, dominantes, buenos oradores, paranoides, megal\u00f3manos, con delirios de grandeza, generadores de fanatismo y algunos con tendencias psic\u00f3ticas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Ciertas sectas pueden ser especialmente alienantes, destructivas o violentas hasta con sus propios seguidores o sus familiares por ejercer un control psicol\u00f3gico o f\u00edsico muy coercitivo sobre los miembros. En ocasiones se les tilda peyorativamente de \u201cherej\u00edas\u201d con relaci\u00f3n al grupo original. Hoy en d\u00eda se les llama con mayor tolerancia \u00abnuevos movimientos religiosos\u00bb. Generan tensi\u00f3n con el grupo de origen u otros grupos. Algunas se crean para gozar de exenciones tributarias o fraude al fisco sobre los dineros del diezmo. Amnist\u00eda Internacional reserva el t\u00e9rmino \u201csecta\u201d para grupos religiosos minoritarios y comprobadamente violentos.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">La posici\u00f3n de los cient\u00edficos sociales sobre\u00a0las\u00a0sectas religiosas<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A una secta se \u201cllega\u201d, pero la aceptaci\u00f3n suele estar condicionada a lealtades sin matices para con l\u00edderes carism\u00e1ticos. Igualmente se puede arribar por la atracci\u00f3n que ejerce lo m\u00e1gico-religioso. En cambio, a\u00a0las\u00a0iglesias se suele llegar por herencia del grupo familiar, por la cultura o atracci\u00f3n de lo sobrenatural, lo terrenal-mundano y hasta por donaciones de consuelo (Max Weber).\u00a0Las\u00a0sectas procuran cierta colaboraci\u00f3n mutua, una firme adhesi\u00f3n ideol\u00f3gico-religiosa, alguna filosof\u00eda y mucho adoctrinamiento ideol\u00f3gico que permita calificar a los miembros del grupo de base abandonados de \u201cblasfemos\u201d o \u201cherejes\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Sobre ellas existen variadas tipolog\u00edas: sectas de \u201crechazo\u201d, de \u201cafirmaci\u00f3n\u201d de la sociedad, \u201cacomodaticias\u201d, del \u201cdespertar,\u201d de \u201csanadores\u201d, \u201corientalistas\u201d, \u201cesot\u00e9ricas\u201d, de \u201cgnosis\u201d, del \u201cpotencial humano\u201d, \u201cconversionistas\u201d, \u201cpol\u00edticas\u201d, \u201cintroversionistas\u201d, \u201cpeligrosas\u201d, \u201cmanipulacionistas\u201d, \u201ctaumat\u00fargicas\u201d, \u201creformistas\u201d, \u201cut\u00f3picas\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En muchas ven los estudiosos un empleo indebido y hasta peligroso de ciertas t\u00e9cnicas de persuasi\u00f3n coercitiva, manipulaci\u00f3n y explotaci\u00f3n que pueden producir da\u00f1o a la personalidad previa del afiliado, sobre todo de aquellos j\u00f3venes alejados de la realidad que han perdido la conciencia. Los feligreses de Sharon Falconer-Gantry ten\u00edan caracter\u00edsticas de secta.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">La secta de Sharon Falconer<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La hermana Falconer reclutaba fieles que deb\u00edan dar el diezmo a cambio de felicidad espiritual. No contaba el grupo todav\u00eda con gente famosa, salvo unos pocos \u201cnotables\u201d provincianos (varios disolutos o corruptos). Ella no gozaba de gran entrenamiento teol\u00f3gico, pero s\u00ed de cierta capacidad de manipulaci\u00f3n psicol\u00f3gico-religiosa en pro de acrecentar una secta en formaci\u00f3n. No se trata de un grupo \u201cdestructivo de control\u201d de tipo religioso. Sin embargo, s\u00ed hubo un episodio violento de orden p\u00fablico contra la carpa y otro contra el propio\u00a0Elmer\u00a0Gantry, tambi\u00e9n se dio el caso de suicidio m\u00edstico por el fuego de Sharon.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El principal m\u00e9todo de seducci\u00f3n empleado por el dueto es la capacidad oratoria y actoral de\u00a0Elmer, as\u00ed como la dulzura y arrobamiento de Sharon, sin olvidar el rol del coro y la m\u00fasica de avivamiento de la hermana Rachel. No existe una evidente jerarqu\u00eda piramidal de orden en la secta sino el carisma de\u00a0Elmer, quien juega con el terrible estado an\u00edmico pre-Gran Depresi\u00f3n (es 1927), el Prohibicionismo, el provincialismo de la regi\u00f3n y la rivalidad entre iglesias y sectas t\u00edpicas del faccionalismo religioso protestante; igualmente la secta de Falconer se pone del lado del puritanismo anti alcohol, anti juego y prostituci\u00f3n, en cuya represi\u00f3n\u00a0Elmer\u00a0sustituye a\u00a0las\u00a0autoridades de polic\u00eda con particular violencia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Juntos, Falconer y Gantry logran cierto control mental a trav\u00e9s del miedo a la condenaci\u00f3n eterna en el infierno; es decir, el cl\u00e1sico discurso \u201cdemonizador del mundo\u201d, acompa\u00f1ado de mimetismo y se\u00f1uelos. El liderazgo inicial de Sharon pronto es asumido por\u00a0Elmer, con desplazamiento de Morgan, secretario titular. El diezmo es exigido con pericia, lo que permiti\u00f3 el r\u00e1pido paso de la carpa al templo de mamposter\u00eda, gracias al carisma, teatralidad y labia de\u00a0Elmer. El fen\u00f3meno de sectas religiosas y de otros tipos es frecuente en el mundo y Colombia no es la excepci\u00f3n.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Iglesias y sectas religiosas de Colombia<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La gran mayor\u00eda de la poblaci\u00f3n sigue siendo cat\u00f3lica, pero existen tendencias ind\u00edgenas, del propio catolicismo y el protestantismo (evang\u00e9licas, pentecostales, anglicanas, bautistas, mormones, adventistas, testigos de Jehov\u00e1 y otras con m\u00e1s de mil pastores). El cristianismo es mayor\u00eda y dentro de este\u00a0las\u00a0iglesias evang\u00e9licas crecen r\u00e1pidamente. Tambi\u00e9n aumentan los Sin religi\u00f3n y\u00a0las\u00a0personas que prefieren No decirlo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Existe hoy en d\u00eda separaci\u00f3n Iglesia-Estado. Antes hubo un Concordato (1887) con el catolicismo como la religi\u00f3n oficial, que fue reformado en 1973. El Protestantismo lleg\u00f3 a mediados del siglo XIX a trav\u00e9s de la Iglesia Presbiteriana. A comienzos del siglo XX llegaron otras iglesias protestantes hist\u00f3ricas, como los bautistas, los menonitas y los evang\u00e9licos. Entre 1932 y 1945 ingresaron los pentecostales, que en ocasiones fueron parcialmente perseguidos. A partir de los a\u00f1os 60, el panorama religioso comienza a cambiar visiblemente en favor de varios grupos protestantes (pentecostalismo fundamentalista y proselitista, la Iglesia de Jesucristo de los Santos de los \u00daltimos D\u00edas, los Adventistas, los Testigos de Jehov\u00e1 y otros).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A finales del siglo XX surgen otras denominaciones as\u00ed como\u00a0las\u00a0megaiglesias cristianas de corte evang\u00e9lico, por obra de la Constituci\u00f3n de 1991, que garantiza la plena libertad de cultos.\u00a0El Ministerio del Interior en 2015 report\u00f3 la existencia de 5.375 iglesias con personer\u00eda jur\u00eddica. En 2019 se reportaron m\u00e1s de 6.000 iglesias cristianas registradas legalmente en todo el territorio nacional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Las\u00a0iglesias colombianas iniciaron desde hace ya un tiempo una participaci\u00f3n en pol\u00edtica, que antes fluctu\u00f3 mayoritariamente entre el Partido Conservador (en favor del catolicismo) y menos en el Liberal (con mayoritaria aproximaci\u00f3n del protestantismo).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A partir de 1991 el cristianismo protestante \u2014confesional y no confesional\u2014 ha participado activamente en pol\u00edtica, al comienzo junto al Partido Liberal Colombiano y luego con vuelo propio. En esta tarea o empresa ha llegado a situar a importantes cantidades de sus pastores y\/o representantes en el Congreso de la Rep\u00fablica,\u00a0las\u00a0Asambleas departamentales y los Concejos municipales. Es as\u00ed como en 2018 se lleg\u00f3 a conformar un partido cristiano protestante. En 2021 se form\u00f3 la primera coalici\u00f3n entre\u00a0dos\u00a0partidos cristianos a fin de participar en\u00a0las\u00a0elecciones legislativas de 2022.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Hoy en d\u00eda existe en Colombia un fuerte proceso de internacionalizaci\u00f3n de algunas organizaciones cristianas (en 2006 m\u00e1s de 10.000 pastores se reunieron en Bogot\u00e1 en congreso internacional). El 4 de julio de 2016 se decret\u00f3 ese d\u00eda de cada a\u00f1o como D\u00eda Nacional de la Libertad Religiosa y de Cultos. Gracias a la Constituci\u00f3n de 1991 Colombia goza de una educaci\u00f3n aconfesional, que proh\u00edbe a todo establecimiento educativo del gobierno dar muestras de inclinaci\u00f3n hacia una religi\u00f3n espec\u00edfica. Se ha observado que, un aspecto cr\u00edtico en materia de sectas es, el \u201cterrenal.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">Lo terrenal de\u00a0las\u00a0sectas religiosas<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Todas parecen tener \u2014pese a su heterogeneidad\u2014 determinantes comunes. Por ejemplo, compiten por \u201ccapitales\u201d simb\u00f3licos en el mercado religioso (que suelen ser privilegios, autoridad, prestigio y riquezas) no sin chocar en ocasiones entre s\u00ed por la apropiaci\u00f3n, monopolizaci\u00f3n o desmonopolizaci\u00f3n. Pol\u00edticamente\u00a0las\u00a0sectas contribuyen al sostenimiento del orden, la legitimaci\u00f3n y perpetuaci\u00f3n de\u00a0las\u00a0estructuras pol\u00edtica seg\u00fan el mandato b\u00edblico de: \u201cDad a Dios lo que es Dios y al C\u00e9sar lo que es del C\u00e9sar\u201d. General y estrat\u00e9gicamente evitan ellas confrontar\u00a0las\u00a0pol\u00edticas del respectivo Estado (a lo que responden algunos grupos armados con acciones violentas de \u201cobjetivo militar\u201d en contra de ministros de religiones y ciertos cuestionamientos de la Teolog\u00eda de la Liberaci\u00f3n). El pluralismo les permite, incita a retener o aumentar sus membres\u00edas no si\u00e9ndoles extra\u00f1as\u00a0las\u00a0estrategias de marketing de reclutamiento de j\u00f3venes y profesionales en competencia a veces ardua y hasta acrimoniosa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Los fieles entregan \u2014en do ut des\u2014 sus capitales humanos, energ\u00edas de trabajo, voluntad y el valioso diezmo, siguiendo los postulados de la \u201cteolog\u00eda de la prosperidad\u201d y la \u201cs\u00faper fe\u201d. Seg\u00fan esta, el dar es como la siembra, el que lo hace con prolijidad cosechar\u00e1 con abundancia y de carambola garantizar\u00e1 para s\u00ed la bendici\u00f3n divina. Por otro lado, reciben a cambio: promesas de compensaci\u00f3n futuras o trascendentales como sanaciones, milagros y desmayos y hasta disfrutar del cielo; beneficios de membres\u00eda como privilegios, contraprestaciones, acceso a capitales sociales y beneficios de sus din\u00e1micas solidarias; as\u00ed mismo reciben otros servicios como bautismos, matrimonios, funerales, visitas a enfermos y consejer\u00edas; no siendo extra\u00f1as ciertas actividades colectivas o bienes comunitarios cuales cultos, coros religiosos, oraciones comunitarias, fiestas religiosas, avivamientos; servicios caritativos a los sectores vulnerables; estatus beneficios econ\u00f3micos y simb\u00f3licos para alcanzar puestos de prestigio, influencia o autoridad dentro del grupo religioso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La colecta del diezmo es lo que m\u00e1s\u00a0las\u00a0favorece, pero tambi\u00e9n les trae toda suerte de cr\u00edticas: De no tributaci\u00f3n o muy laxa al Estado (preocupaci\u00f3n de la DIAN en Colombia y de ciertas tendencias progresistas en el mundo de\u00a0las\u00a0ideolog\u00edas); por casos escandalosos de enriquecimiento desmedido de ciertos l\u00edderes, lo que ha llevado a que se hable de \u201cempresas y proyectos religiosos\u201d con \u00e1nimo de lucro (casos de\u00a0las\u00a0megaiglesias movilizadoras de fieles y de los templos millonarios).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Tambi\u00e9n hay cierto temor de parte de los l\u00edderes y partidos pol\u00edticos colombianos al costo pol\u00edtico de pedir a los grupos religiosos no cat\u00f3licos el pago de un impuesto para la paz que \u2014en opini\u00f3n de algunos\u2014 podr\u00eda ser considerado como una contraprestaci\u00f3n de ellos al Concordato Evang\u00e9lico o Decreto 354 de 1998 y a los privilegios que se les otorg\u00f3 en varias materias. Empero, de acuerdo a la libertad constitucional de cultos todas\u00a0las\u00a0dem\u00e1s iglesias reciben el mismo trato de la Iglesia cat\u00f3lica que es declarante, pero no contribuyente, condici\u00f3n que ella tampoco aceptar\u00eda.<\/span><\/p>\n<h3 class=\"wp-block-heading\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\">El creciente inter\u00e9s universal por el fen\u00f3meno de\u00a0las\u00a0sectas religiosas<\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es inter\u00e9s de los medios de comunicaci\u00f3n, academias, asociaciones culturales o de familia y hasta de los partidos pol\u00edticos seculares. En el caso del cine y de\u00a0las\u00a0llamadas \u201cdocuseries\u201d hay varias producciones que muestran o denuncian casos de sectas religiosas que abusan de los derechos humanos y la libertad de conciencia de sus miembros. Por ejemplo, en Netflix algunos documentales han hecho importantes denuncias. Es el caso de C\u00f3mo se convirtieron en l\u00edderes de sectas, que versa sobre seis personajes pol\u00e9micos de la historia que se convirtieron en peligrosos l\u00edderes sectarios, todos ellos h\u00e1biles manipuladores de la mente de sus reba\u00f1os, inmensamente ricos, depredadores sexuales que han enga\u00f1ado bajo la promesa de la eternidad, de cultivar una buena imagen o de alcanzar alg\u00fan tipo de inmortalidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En Jo\u00e3o de Deus. Curandero y criminal, un m\u00e9dium cosecha fama internacional de hacer sanaciones y avivamientos, hasta que los sobrevivientes, fiscales y la prensa revelan sus terribles abusos en diezmos, sexo y estafas. En el nombre de Dios. Sagrada traici\u00f3n, se muestra el lado oscuro de la fe incondicional a trav\u00e9s de\u00a0las\u00a0escalofriantes y reales historias de sexo, crueldad y diezmos de cuatro supuestos profetas coreanos. La docuserie Colonia Dignidad. Una secta alemana en Chile, muestra una liderada por un pastor carism\u00e1tico refugiado de Alemania, que se convierte en c\u00f3mplice de la dictadura de Pinochet. La pel\u00edcula\u00a0Elmer\u00a0Gantry puede verse completa en espa\u00f1ol Latino y gratis en internet.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En el prefacio de la edici\u00f3n francesa, 1932, el ensayista americano H. L. Mencken declara que a su juicio\u00a0Elmer\u00a0Gantry es la mejor obra de Lewis, y a\u00f1ade: \u201cLa recomiendo a los franceses quiz\u00e1 como el mejor cuadro de la vida americana que jam\u00e1s haya sido proyectado sobre el papel; un cuadro espantoso, pero verdadero\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Para otros Gantry es una mezcla de Gil Blas y Tartufo. Ciertamente, la s\u00e1tira de Lewis no solo era necesaria en esa \u00e9poca sino que lo es todav\u00eda en este siglo XXI donde la hipocres\u00eda y esc\u00e1ndalos de ciertas sectas pseudorreligiosas ofenden sentimientos democr\u00e1ticos y tienen un efecto perverso de manipulaci\u00f3n de\u00a0las\u00a0conciencias si se tiene en cuenta que los bienes religiosos que suelen ofrecer Iglesias serias y respetables tienen valor para legiones de feligreses que han encontrado en ellos cierto sentido de grupo familiar de apoyo o terap\u00e9utico \u2014no estatal\u2014 que crea\u00a0las\u00a0solidaridades y los beneficios que cada uno puede y debe valorar en la intimidad de su conciencia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es decir, lo que protege el n\u00facleo de derechos garantizados en Colombia por la combinaci\u00f3n de los art\u00edculos 18 y 19 de la Constituci\u00f3n Pol\u00edtica, textos que son violados sin misericordia ni piedad alguna por ep\u00edgonos descarriados de\u00a0Elmer\u00a0Gantry.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2303574\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-1-213x300.jpg\" alt=\"\" width=\"280\" height=\"394\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-1-213x300.jpg 213w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2024\/11\/elmer-gantry-cartel-largo-1.jpg 710w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/puntocritico.com\/ausajpuntocritico\/author\/punto-critico\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9528\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2018\/03\/Mosca_Punto_Cr\u00edtico_40.png\" alt=\"\" width=\"80\" height=\"80\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>EL FUEGO Y LA PALABRA (\u00abElmer Gantry\u00bb) &nbsp; El fuego y la palabra \u2018El fuego y la palabra\u2019 (Elmer Gantry, 1960), de Richard Brooks, es una corrosiva, y exultante, obra que pone en cuesti\u00f3n la <a class=\"mh-excerpt-more\" href=\"https:\/\/puntocritico.com\/ausajpuntocritico\/2024\/11\/30\/el-fuego-y-la-palabra-elmer-gantry-pelicula-de-richard-brooks-1-960\/\" title=\"EL FUEGO Y LA PALABRA (\u00abElmer Gantry\u00bb). Pel\u00edcula de Richard Brooks (1.960)\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":2303564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2303233","post","type-post","status-publish","format-standard","has-post-thumbnail","category-miscelanea"],"acf":[],"_links":{"self":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/posts\/2303233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/comments?post=2303233"}],"version-history":[{"count":0,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/posts\/2303233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/media\/2303564"}],"wp:attachment":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/media?parent=2303233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/categories?post=2303233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/tags?post=2303233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}