{"id":20115,"date":"2019-07-15T00:05:30","date_gmt":"2019-07-14T23:05:30","guid":{"rendered":"https:\/\/puntocritico.com\/ausajpuntocritico\/?p=20115"},"modified":"2019-07-13T17:07:42","modified_gmt":"2019-07-13T16:07:42","slug":"el-caso-woody-allen-un-hijo-toma-la-palabra-por-moses-farrow","status":"publish","type":"post","link":"https:\/\/puntocritico.com\/ausajpuntocritico\/2019\/07\/15\/el-caso-woody-allen-un-hijo-toma-la-palabra-por-moses-farrow\/","title":{"rendered":"\u00abEl caso Woody Allen: Un hijo toma la palabra\u00bb, por Moses Farrow"},"content":{"rendered":"<section id=\"feature\">\n<header class=\"article-header article-foto_ep\">\n<div class=\"title-wrapp\">\n<div class=\"container\">\n<div class=\"col-md-9\">\n<div class=\"article-title title-foto_ep\">\n<blockquote>\n<h1 style=\"text-align: center;\"><span style=\"font-size: 24pt;\">Cr\u00e9dito y cinismo: el valor social de la verdad<\/span><\/h1>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/header>\n<\/section>\n<blockquote>\n<div class=\"article-abstract\" style=\"text-align: center;\"><span style=\"font-size: 14pt;\"><strong><em><span style=\"font-size: 18pt; color: #008000;\">Hemos transformado el debate p\u00fablico en una enfermedad autoinmune que, en lugar de proteger y fortalecer el sistema, lo ataca<\/span>.\u00a0<\/em><\/strong><\/span><\/div>\n<div class=\"top-share\">\n<div class=\"addthis_sharing_toolbox\" data-url=\"https:\/\/www.letraslibres.com\/espana-mexico\/politica\/credito-y-cinismo-el-valor-social-la-verdad\" data-title=\"Cr\u00e9dito y cinismo: el valor social de la verdad\" data-description=\"Hemos transformado el debate p\u00fablico en una enfermedad autoinmune que, en lugar de proteger y fortalecer el sistema, lo ataca.\u00a0\">\n<div role=\"region\" aria-labelledby=\"at-d7d0bc81-6f59-499d-8f04-2020ed637372\">\u00a0<\/div>\n<div id=\"atstbx2\" class=\"at-share-tbx-element addthis-smartlayers addthis-animated at4-show\" role=\"region\" aria-labelledby=\"at-d7d0bc81-6f59-499d-8f04-2020ed637372\">Por Elena Alfaro<\/div>\n<div role=\"region\" aria-labelledby=\"at-d7d0bc81-6f59-499d-8f04-2020ed637372\">\u00a0<\/div>\n<\/div>\n<\/div>\n<div role=\"region\" aria-labelledby=\"at-d7d0bc81-6f59-499d-8f04-2020ed637372\">\u00a0<\/div>\n<div role=\"region\" aria-labelledby=\"at-d7d0bc81-6f59-499d-8f04-2020ed637372\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20123\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/14-768x1149-201x300.jpg\" alt=\"\" width=\"201\" height=\"300\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/14-768x1149-201x300.jpg 201w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/14-768x1149.jpg 428w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/div>\n<div role=\"region\" aria-labelledby=\"at-d7d0bc81-6f59-499d-8f04-2020ed637372\">\u00a0<\/div>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El 7 de agosto de 2009, Sarah Palin, candidata republicana a la vicepresidencia de Estados Unidos, public\u00f3 un post en su cuenta de Facebook alertando sobre el peligro de las propuestas del Obamacare. Relacionaba medidas de racionalizaci\u00f3n del gasto sanitario con el asesoramiento voluntario sobre cuidados paliativos y testamento vital. Conclu\u00eda que si entraban en vigor las medidas que se apuntaban en el proyecto de ley de Obama se crear\u00edan \u201ctribunales de la muerte\u201d que decidir\u00edan qui\u00e9nes merec\u00edan atenci\u00f3n sanitaria y qui\u00e9nes no.<\/span><\/p>\n<p style=\"padding-left: 40px; text-align: justify;\"><span style=\"font-size: 14pt;\">\u00bfY qui\u00e9nes ser\u00e1n los que m\u00e1s sufran cuando se racionen los cuidados? Los enfermos, los ancianos y los discapacitados, por supuesto. Los Estados Unidos que conozco y amo no es un pa\u00eds en el que mis padres o mi hijo con s\u00edndrome de Down tengan que presentarse ante el \u201ctribunal de la muerte\u201d de Obama para que sus bur\u00f3cratas puedan decir, a partir de un juicio subjetivo de su \u201cnivel de productividad en la sociedad\u201d, si son merecedores de tener acceso a la atenci\u00f3n sanitaria. Ese sistema es simplemente malvado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La web\u00a0<a href=\"https:\/\/www.politifact.com\/truth-o-meter\/statements\/2009\/aug\/10\/sarah-palin\/sarah-palin-barack-obama-death-panel\/\" target=\"_blank\" rel=\"noopener\">Politifact<\/a>\u00a0explic\u00f3 la tergiversaci\u00f3n tan solo tres d\u00edas despu\u00e9s,\u00a0el 10 de agosto, y la calific\u00f3 de\u00a0<em>pants on fire<\/em>, el m\u00e1ximo galard\u00f3n que una mentira puede recibir.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Matthew d\u2019Ancona recoge la historia en su libro\u00a0<em>Posverdad. La nueva guerra contra la verdad y c\u00f3mo combatirla<\/em>\u00a0(Alianza Editorial, 2019) y a\u00f1ade una inquietante informaci\u00f3n: siete d\u00edas despu\u00e9s de la publicaci\u00f3n del post (y cuatro del desmentido) cerca del 90% de los estadounidenses conoc\u00eda el asunto. De ellos el 30% cre\u00eda lo que Palin dec\u00eda. El art\u00edculo malinterpretado fue retirado de la ley. En 2012, se\u00f1ala d\u2019Ancona, el n\u00famero de ciudadanos que cre\u00edan en los \u201ctribunales de la muerte\u201d hab\u00eda aumentado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Hace unos d\u00edas, el Partido Popular hizo una propuesta un tanto extempor\u00e1nea. Propon\u00eda llevar a nivel de ley nacional determinadas actuaciones incluidas en el protocolo de adopci\u00f3n que lleva muchos a\u00f1os aplic\u00e1ndose, por ejemplo, en <a href=\"https:\/\/s03.s3c.es\/imag\/doc\/2019-03-14\/PROTOCOLO-HOSPITALES-ADOPCION-DGFM.pdf\" target=\"_blank\" rel=\"noopener\">Madrid<\/a>. Dicho protocolo garantiza la confidencialidad de los datos de las mujeres que desean dar en adopci\u00f3n a su hijo y no hace diferencia alguna sobre la situaci\u00f3n legal de la madre biol\u00f3gica, tan solo a\u00f1ade que si la madre es extranjera, puede manifestar su deseo de que se contacte con sus familiares o autoridades consulares para que se hagan cargo del beb\u00e9. El Partido Popular anunci\u00f3 su propuesta de una forma tosca y centr\u00e1ndose en prevenir, sin m\u00e1s explicaci\u00f3n, las consecuencias indeseables que se producen cuando dicha confidencialidad no se garantiza y dar a un hijo en adopci\u00f3n puede conllevar delatar una situaci\u00f3n irregular ante las autoridades.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Esta medida apenas tendr\u00eda impacto en Espa\u00f1a y parece responder a situaciones importadas de otros pa\u00edses (por ejemplo EEUU, donde\u00a0<a href=\"https:\/\/elpais.com\/internacional\/2017\/03\/05\/actualidad\/1488687145_565202.html\" target=\"_blank\" rel=\"noopener\">California<\/a>\u00a0impulsa leyes en las que sus autoridades tienen prohibido compartir informaci\u00f3n con la polic\u00eda migratoria).\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La propuesta del PP se interpret\u00f3 bajo la luz m\u00e1s desfavorable posible: te cambiamos a tu hijo por papeles.\u00a0Al igual que suced\u00eda con la versi\u00f3n que Palin hac\u00eda de las propuestas de Obama, era posible hacer esa interpretaci\u00f3n. S\u00ed, pero solo bajo la premisa de estar tratando con aut\u00e9nticos desalmados sin escr\u00fapulos. Adem\u00e1s de perversos, idiotas que exponen en p\u00fablico sus ideas retorcidas e inhumanas.\u00a0Cuando uno cree que Obama es capaz de facilitar que los \u201cmenos aptos\u201d sean invitados a quitarse la vida es posible entender cualquier monstruosidad en la letra de una ley que trata temas delicados sobre el dolor o la desesperaci\u00f3n ante la enfermedad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Obama no es un monstruo. Casado tampoco lo es. Por mucho que uno nos pueda parecer un gigante y el otro un advenedizo sin fundamento, hemos llegado a una situaci\u00f3n tal de animadversi\u00f3n y apego a los colores propios que hacemos de lo enloquecido algo veros\u00edmil.\u00a0Y lo que es peor, aunque sepamos que probablemente nuestra versi\u00f3n es falsa, no parece preocuparnos: solo importa aprovechar el hueco que el rival ha dejado abierto y asestar el golpe. Pero lo que tomamos por victoria hoy es una derrota segura ma\u00f1ana mismo (<em>not wrong too long<\/em>, dec\u00edan en la Fox).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Todo esto tiene que ver con la verdad, la confianza y el cr\u00e9dito. Dice D\u2019Ancona, a prop\u00f3sito de Rusia, que la acumulaci\u00f3n de mentiras sin consecuencias lleva al ciudadano a la conclusi\u00f3n de que los mentirosos tienen el poder de definir lo que es real. Que el puro agotamiento puede \u201cdespojar de su compromiso con la verdad incluso al ciudadano vigilante\u201d. En un proceso que tiene distintas fases pasamos de la indignaci\u00f3n a la indiferencia para acabar, lamentablemente, en la complicidad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Esa complicidad muestra distintas caras. Una de ellas es la complicidad pasiva, muchas veces simple cansancio, de los espectadores. Los que dimitimos del esfuerzo intelectual y, perezosamente, permitimos que la \u201cverdad\u201d que nos conviene creer sea algo que de verdad creemos.\u00a0La otra es la complicidad activa; la de medios y personalidades, la de los titulares de opiniones de prestigio que anta\u00f1o nos serv\u00edan de referencia ante cuestiones complejas y hoy, dimitiendo de su funci\u00f3n primigenia, utilizan su p\u00falpito para respaldar una opci\u00f3n pol\u00edtica. En muchos casos sonroja ver en acci\u00f3n el viejo truco de disfrazar de honda preocupaci\u00f3n lo que no es m\u00e1s que una agenda concreta.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En otro momento esclarecedor del libro, el autor se\u00f1ala que cuando se pierde el valor social de la verdad tambi\u00e9n desaparecen las pr\u00e1cticas sociales basadas en ella. Una de las primeras v\u00edctimas ha sido el debate p\u00fablico. Nunca en la historia hemos dispuesto de herramientas m\u00e1s potentes para intercambiar, difundir y acceder a opiniones informadas. Nunca antes hab\u00eda sido posible interactuar de manera tan sencilla, ir a las fuentes, o escuchar a otros que saben mucho de alguna cosa. Pero en lugar de sabios nos hemos vuelto c\u00ednicos: \u201cun relativismo malsano donde (&#8230;) la cuesti\u00f3n se reduce a mantener vivo el debate y asegurarse de que nunca llegue a una conclusi\u00f3n\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Sam Smith dijo en 1995:<\/span><\/p>\n<p style=\"padding-left: 40px; text-align: justify;\"><span style=\"font-size: 14pt;\">El poeta comprende que un mito no es una mentira, sino la versi\u00f3n que tiene el alma de la verdad. Uno de los motivos de que hoy en d\u00eda los medios destrocen tantas noticias es que los periodistas se han vuelto incapaces de manejar todo lo que no sea literal.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En este estado de cosas nadie se atrever\u00e1 a exponer una idea \u201crica o extra\u00f1a\u201d. No se hablar\u00e1 de pol\u00edticas porque antes de llegar a ellas todo es ya una cuesti\u00f3n pol\u00edtica. Las herramientas que dise\u00f1amos para protegernos de los espejismos y las conclusiones demasiado \u201cintuitivas\u201d se utilizan para desacreditar la verdad a fuerza de simplificarla y convertirla en algo binario.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Hemos transformado el debate p\u00fablico en una enfermedad autoinmune que, en lugar de proteger y fortalecer el sistema, lo ataca.\u00a0Por eso el intercambio c\u00ednico es un resultado esperable. Por eso tambi\u00e9n negarse a participar en \u00e9l puede resultar una actitud provocadora.\u00a0Posverdad y polarizaci\u00f3n son dos caras de la misma moneda, dependientes una de la otra, que producen los mismos ganadores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Dec\u00eda Tyler Cowen en un optimista art\u00edculo en\u00a0<a href=\"https:\/\/www.bloomberg.com\/opinion\/articles\/2019-03-18\/on-big-tech-and-brexit-polarization-isn-t-as-bad-as-it-looks\" target=\"_blank\" rel=\"noopener\">Bloomberg<\/a>\u00a0que percibe se\u00f1ales de que el ciclo polarizador pueda estar empezando a quebrarse. Ojal\u00e1 tenga raz\u00f3n, pero los argumentos en los que se apoya para creerlo no son nuevos. La cercan\u00eda de opiniones ante numerosas cuestiones ya exist\u00eda antes. Lilliana Mason, entre muchos otros, lo ha mostrado en\u00a0<em>Uncivil agreement. How politics became our identity<\/em>: \u201cHemos pasado de dos partidos que difer\u00edan un poco en muchos asuntos a dos partidos que difieren mucho en pocos, pero poderosos, temas\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Mientras no se recupere el valor social de la verdad, importar\u00e1 mucho m\u00e1s qui\u00e9n y c\u00f3mo nos pregunte que lo que nos pregunte. No parece que las herramientas que utilizamos para comprobar la veracidad de las noticias ni las opiniones de los m\u00e1s prudentes vayan a sacarnos de este c\u00edrculo vicioso. Posiblemente, como concluye D\u2019Ancona, la \u00fanica salida pase necesariamente por el compromiso sostenido y obstinado de los ciudadanos con que la verdad siga siendo importante para nosotros como civilizaci\u00f3n.<\/span><\/p>\n<p style=\"text-align: right;\"><a href=\"https:\/\/www.letraslibres.com\/espana-mexico\/politica\/credito-y-cinismo-el-valor-social-la-verdad\" target=\"_blank\" rel=\"noopener\">https:\/\/www.letraslibres.com\/espana-mexico\/politica\/credito-y-cinismo-el-valor-social-la-verdad<\/a><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 14pt; color: #008000;\">\u2666\u2666\u2666\u2666\u2666<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20121\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Woody-Allen-Y-Moses-farrow.jpg\" alt=\"\" width=\"440\" height=\"246\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 24pt;\"><strong>\u00abEl caso Woody Allen: Un hijo toma la palabra\u00bb<\/strong><\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"font-size: 14pt;\">Por Moses Farrow<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"article-abstract\" style=\"text-align: center;\"><span style=\"font-size: 18pt; color: #008000;\"><em><strong>Moses Farrow, el hijo de Woody Allen y Mia Farrow, defiende a su padre contra las acusaciones de pederastia y describe una infancia traum\u00e1tica con su madre\u00a0<\/strong><\/em><\/span><\/div>\n<div class=\"at-share-tbx-element addthis-smartlayers addthis-animated at4-show\" style=\"text-align: justify;\" role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\u00a0<\/div>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Soy una persona muy reservada y no me interesa en absoluto la atenci\u00f3n del p\u00fablico. Pero, ante los ataques incre\u00edblemente err\u00f3neos y enga\u00f1osos hacia mi padre, Woody Allen, me parece que no puedo permanecer en silencio mientras se le condena por un crimen que no cometi\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Estuve presente ante todo lo que sucedi\u00f3 en nuestra casa antes, durante y despu\u00e9s del supuesto acontecimiento. Ahora que la histeria p\u00fablica de comienzos de este a\u00f1o se ha apagado un poco y tengo algo de esperanza de que la verdad pueda ser escuchada, quiero compartir mi historia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El 4 de agosto de 1992 era un d\u00eda c\u00e1lido y soleado en Bridgewater, Connecticut, pero en nuestra casa familiar, Frog Hollow, hab\u00eda un escalofr\u00edo en el aire. Mi madre, Mia Farrow, hab\u00eda salido a comprar con su amiga de la infancia, Casey Pascal. Yo ten\u00eda catorce a\u00f1os, y estaba en casa con mi hermana peque\u00f1a, Dylan, que acababa de cumplir siete a\u00f1os; mi hermano Satchel, que ten\u00eda cuatro a\u00f1os y ahora se llama Ronan, y los tres hijos de Casey. Nos vigilaba nuestra ni\u00f1era, Kristi, as\u00ed como la ni\u00f1era de Casey, Alison, y nuestra profesora de franc\u00e9s, Sophie. La casa estaba llena.<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20118 size-full\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Woody-Allen-y-Soon-yi.jpeg\" alt=\"\" width=\"630\" height=\"315\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Woody-Allen-y-Soon-yi.jpeg 630w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Woody-Allen-y-Soon-yi-300x150.jpeg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\">Woody Allen y Soon-yi\u00a0<\/span><\/p>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p>&nbsp;<\/p>\n<\/div>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Hab\u00eda otro adulto en la sala de la tele aquel d\u00eda, sentado en el suelo, viendo\u00a0<em>\u00bfQui\u00e9n enga\u00f1\u00f3 a Roger Rabbit?<\/em>, con el resto de nosotros: Woody Allen. En apariencia, no era diferente a sus visitas anteriores a nuestra casa de campo. Pero mi madre nos hab\u00eda avisado de que no deb\u00edamos perderlo de vista. Estaba comprensiblemente furiosa: siete meses antes se hab\u00eda enterado de que ten\u00eda una relaci\u00f3n \u00edntima con mi hermana de veinti\u00fan a\u00f1os, Soon-Yi, tras descubrir Polaroids de ella en el apartamento de Woody. Durante meses nos hab\u00eda estado taladrando las cabezas como un mantra: Woody era \u201cmalvado\u201d, \u201cun monstruo\u201d, \u201cel diablo\u201d, y Soon-Yi estaba \u201cmuerta para nosotros\u201d. Este era el estribillo constante, daba igual que estuviera Woody o no. (Lo repet\u00eda con tanta frecuencia que Satchel le anunci\u00f3 a una de nuestras ni\u00f1eras: \u201cMi hermana se est\u00e1 follando a mi padre\u201d. Satchel acababa de cumplir cuatro a\u00f1os.) Mi madre era nuestra \u00fanica fuente de informaci\u00f3n sobre Woody, y era extremadamente convincente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Como el mayor de los hijos en la casa en ese d\u00eda de verano, me tomaba muy en serio las advertencias de Mia. Pensaba que mi trabajo era apoyar a mi madre y quer\u00eda desesperadamente su aprobaci\u00f3n, como todos sus hijos. Tambi\u00e9n hab\u00eda aprendido en repetidas ocasiones que ir contra sus deseos ten\u00eda repercusiones. Estar\u00eda pendiente de Woody hasta que volviera mi madre. Pero en secreto estaba desgarrado.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Para ayudar a explicar por qu\u00e9, voy a dar un poco de informaci\u00f3n sobre nuestra familia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Aunque Woody y Mia nunca se casaron -y \u00e9l nunca vivi\u00f3 con nosotros ni se quedaba a dormir en nuestro apartamento en la ciudad- sol\u00eda venir a las 6:30 de la ma\u00f1ana, con dos peri\u00f3dicos y un pu\u00f1ado de magdalenas. Yo me levantaba antes de los dem\u00e1s, y \u00e9l y yo nos sent\u00e1bamos en la mesa de la cocina juntos para desayunar. Mientras le\u00eda\u00a0<em>The New York Times<\/em>, yo cog\u00eda el\u00a0<em>Post<\/em>\u00a0e iba directo a los c\u00f3mics y los crucigramas. Pas\u00e1bamos un rato tranquilos antes de despertar a Dylan. Le hac\u00eda un par de tostadas con canela o miel y se quedaba mientras ella desayunaba. No ten\u00eda mucha pinta de monstruo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Mis hermanos mayores eran todos hijos biol\u00f3gicos o adoptados de Mia y su exmarido Andr\u00e9 Previn. En 1985 Mia adopt\u00f3 a Dylan. Dos a\u00f1os m\u00e1s tarde ella y Woody tuvieron a su \u00fanico hijo biol\u00f3gico, Satchel. A los cuarenta y nueve a\u00f1os, Woody parec\u00eda encantado con su nuevo papel de padre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Mia me hab\u00eda adoptado a m\u00ed, su s\u00e9ptimo hijo, como madre soltera en 1980. En 1992 pidi\u00f3 y consigui\u00f3 que Woody Allen nos coadoptara a Dylan y m\u00ed: escribi\u00f3 a la agencia de adopci\u00f3n, explicaba que era un padre excelente. Yo estaba encantado cuando Woody se convirti\u00f3 oficialmente en mi padre, porque ya hab\u00eda asumido ese papel en mi vida. Jug\u00e1bamos a la pelota y al ajedrez, ech\u00e1bamos unas canastas. A medida que pasaban los a\u00f1os, Satchel, Dylan y yo nos hicimos visitantes frecuentes de sus lugares de rodaje y su sala de montaje. Por las tardes, ven\u00eda al apartamento de Mia y pasaba tiempo con nosotros. Nunca vi nada que indicara un comportamiento inadecuado en ning\u00fan momento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Luego, por supuesto, las noticias de Woody y Soon-Yi se hicieron p\u00fablicas, y todo cambi\u00f3. Mi madre insisti\u00f3 en que sac\u00e1ramos a los dos de nuestras vidas, y no tuvimos otra opci\u00f3n que aceptarlo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Incluso la gente que duda de las acusaciones de abusos de Dylan se aferra a la relaci\u00f3n de Woody con Soon-Yi como justificaci\u00f3n por su escepticismo hacia \u00e9l. Los ataques p\u00fablicos a Soon-Yi de completos desconocidos todav\u00eda me desconciertan, as\u00ed como la desinformaci\u00f3n general que tanta gente considera hechos. No es la hija de Woody (ni adoptada, ni hijastra ni ninguna otra cosa), ni tiene problemas de desarrollo mental. (\u00a1Tiene un m\u00e1ster en educaci\u00f3n especial por la Universidad de Columbia!) Y la idea de que empezaron a citarse cuando ella era menor de edad es totalmente falsa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En realidad, Woody y Soon-Yi apenas hablaron durante su ni\u00f1ez. Fue mi madre quien sugiri\u00f3, cuando Soon-Yi ten\u00eda veinte a\u00f1os, que Woody Allen pasara tiempo con ella. \u00c9l lo acept\u00f3 y empez\u00f3 a llevarla a partidos de los Knicks. As\u00ed es como empez\u00f3 su romance. S\u00ed, era heterodoxo, inc\u00f3modo, disruptivo para nuestra familia y le hizo a mi madre un da\u00f1o terrible. Pero la relaci\u00f3n en s\u00ed no fue ni de lejos tan devastadora como la insistencia de mi madre en colocar esta traici\u00f3n en el centro de nuestras vidas desde entonces en adelante.<\/span><\/p>\n<\/div>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Pero la disfunci\u00f3n fatal de la casa de mi infancia no ten\u00eda nada que ver con Woody. Empez\u00f3 mucho antes de que apareciera y llegaba directamente de una oscuridad profunda y persistente en la familia Farrow.<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20128\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/John_Farrow_family_1950-300x237.jpg\" alt=\"\" width=\"510\" height=\"403\" srcset=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/John_Farrow_family_1950-300x237.jpg 300w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/John_Farrow_family_1950-768x607.jpg 768w, https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/John_Farrow_family_1950.jpg 826w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\">John Farrow con su familia, 1950<\/span><\/p>\n<p>&nbsp;<\/p>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Era bien sabido en Hollywood que mi abuelo, el director John Farrow, era un bebedor notorio y muy mujeriego. Hubo muchas peleas regadas con alcohol entre sus padres, y Mia me dijo que sufri\u00f3 intentos de abuso en su propia familia. Su hermano, mi t\u00edo John, que nos ven\u00eda a ver a menudo cuando \u00e9ramos peque\u00f1os, est\u00e1 en la c\u00e1rcel condenado por m\u00faltiples acusaciones de abuso infantil. (Mi madre nunca ha hablado en p\u00fablico sobre esto, ni ha expresado ninguna preocupaci\u00f3n por las v\u00edctimas de su hermano.) Mi t\u00edo Patrick y su familia ven\u00edan a menudo, pero esas visitas pod\u00edan terminar abruptamente porque Mia y Patrick terminaban discutiendo con frecuencia. Mi t\u00edo Patrick se suicid\u00f3 en 2009.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Mi madre, por supuesto, ten\u00eda su propia oscuridad. Se cas\u00f3 con Frank Sinatra, que en ese momento ten\u00eda cincuenta a\u00f1os, cuando ella solo ten\u00eda veintiuno. Despu\u00e9s del divorcio, se mud\u00f3 a casa de su amiga \u00edntima Dory Previn y su marido, Andr\u00e9. Cuando mi madre qued\u00f3 embarazada de Andr\u00e9, el matrimonio de los Previn se rompi\u00f3, lo que produjo el ingreso en el psiqui\u00e1trico de Dory. Nunca se habl\u00f3 de esto en nuestra casa, por supuesto, y yo no lo supe hasta hace unos a\u00f1os. Pero, al observarlo ahora -como terapeuta adem\u00e1s de como testigo- me doy cuenta de que era f\u00e1cil ver las semillas de disfunci\u00f3n que germinar\u00edan en nuestra casa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Para mi madre era importante proyectar hacia el mundo una imagen de un hogar bien amasado de hijos biol\u00f3gicos y adoptados, pero eso estaba lejos de la verdad. Estoy seguro de que mi madre ten\u00eda buenas intenciones al adoptar a ni\u00f1os con discapacidades que ven\u00edan de las circunstancias m\u00e1s duras, pero la realidad entre las paredes de nuestra casa era muy distinta. Me duele recordar ejemplos en los que vi a mis hermanos, algunos ciegos o f\u00edsicamente discapacitados, arrastrados por las escaleras para ser arrojados a un dormitorio o un armario, que luego se cerraba con llave desde fuera. Mia lleg\u00f3 a encerrar a mi hermano Thaddeus, parapl\u00e9jico porque hab\u00eda sufrido la polio, en un cobertizo en el exterior para castigarlo por una transgresi\u00f3n menor.<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20124\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Woody-Allen-y-Mia-Farrow.jpg\" alt=\"\" width=\"396\" height=\"244\" \/><\/p>\n<p>&nbsp;<\/p>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Soon-Yi era su chivo expiatorio m\u00e1s frecuente. Mi hermana ten\u00eda un esp\u00edritu independiente y, de todos nosotros, era la que se sent\u00eda menos intimidada por Mia. Cuando se ve\u00eda obligada, reprochaba a mi madre su comportamiento y se produc\u00edan feas discusiones. Cuando Soon-Yi era peque\u00f1a, Mia le hab\u00eda tirado un centro de mesa de porcelana a la cabeza. Por fortuna, fall\u00f3, pero los fragmentos de la pieza rota le dieron en las piernas. A\u00f1os despu\u00e9s, le peg\u00f3 con el auricular de un tel\u00e9fono. Soon-Yi dej\u00f3 claro que su deseo era sencillamente que la dejara en paz, lo que cada vez fue m\u00e1s com\u00fan. Aunque su relaci\u00f3n con Woody era poco convencional, fue lo que le permiti\u00f3 escapar. Otros no tuvieron tanta suerte.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La mayor parte de los medios dicen que mi hermana Tam muri\u00f3 de un \u201cfallo cardiaco\u201d a los 21 a\u00f1os. En realidad, Tam luch\u00f3 contra la depresi\u00f3n la mayor parte de su vida, una situaci\u00f3n exacerbada por que mi madre se negaba a que la atendieran, insistiendo en que solo estaba \u201cfloja\u201d. Una tarde del a\u00f1o 2000, tras una pelea final con Mia, que termin\u00f3 cuando mi madre se fue de casa, Tam se sucidi\u00f3 con una sobredosis de pastillas. Mi madre cont\u00f3 a los dem\u00e1s que la sobredosis fue accidental, y dijo que Tam, que era ciega, no sab\u00eda qu\u00e9 pastillas tomaba. Pero Tam ten\u00eda una memoria estupenda y sentido de reconocimiento espacial. Y, por supuesto, la ceguera no le imped\u00eda contar.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Los detalles de la sobredosis de Tam y la discusi\u00f3n con Mia que la precipitaron me los comunic\u00f3 directamente mi hermano Thaddeus, que fue testigo de los hechos. Tr\u00e1gicamente, ya no puede confirmar esta versi\u00f3n. Hace dos a\u00f1os, Thaddeus tambi\u00e9n se suicid\u00f3 dispar\u00e1ndose en su coche, a menos de diez minutos de la casa de mi madre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Mi hermana Lark tambi\u00e9n falleci\u00f3. Entr\u00f3 en un camino de autodestrucci\u00f3n, luch\u00f3 contra la adicci\u00f3n y finalmente muri\u00f3 en la indigencia por causas relacionadas con el sida en 2008, a los 35 a\u00f1os.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Para todos nosotros, la vida en la casa de mi madre era imposible si no hac\u00edas exactamente lo que te dec\u00edan, por discutible que fuera la demanda.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">El verano entre los cursos de primero y segundo, estaban poniendo nuevo papel de pared en la habitaci\u00f3n donde yo dorm\u00eda, al otro lado del pasillo en el segundo piso de nuestra casa en Connecticut. Yo me preparaba para ir a dormir, cuando mi madre vino a mi cama y encontr\u00f3 una cinta m\u00e9trica. Me dirigi\u00f3 una mirada penetrante y me pregunt\u00f3 si me la hab\u00eda llevado, porque se hab\u00eda pasado el d\u00eda busc\u00e1ndola. Le dije que no lo sab\u00eda, que quiz\u00e1 se la hab\u00eda dejado uno de los obreros. Me pregunt\u00f3 una y otra vez, una y otra vez.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Cuando no le respond\u00ed lo que quer\u00eda, me abofete\u00f3, tir\u00e1ndome las gafas al suelo. Me dijo que estaba mintiendo y me dijo que fuera a decirles a mis hermanos que me hab\u00eda llevado la cinta m\u00e9trica. Entre l\u00e1grimas escuch\u00e9 mientras ella me explicaba que ensayar\u00edamos un relato sobre lo que deber\u00eda haber pasado. Ella entrar\u00eda en la habitaci\u00f3n y yo dir\u00eda que sent\u00eda haber cogido la cinta m\u00e9trica, que me la hab\u00eda llevado para jugar y que no lo volver\u00eda a hacer. Me hizo repetirlo al menos media docena de veces.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Ese fue el comienzo de sus entrenamientos, repeticiones, guionizaciones y ensayos: en esencia, lavados de cerebro. Me sent\u00eda ansioso y asustado. Una vez, cuando me regalaron unos vaqueros nuevos, pens\u00e9 que quedar\u00edan mejor si cortaba un par de trabillas. Cuando Mia vio lo que hab\u00eda hecho, me azot\u00f3 repetidamente y me hizo que me quitara toda la ropa, diciendo: \u201cNo mereces ninguna prenda\u201d, y me oblig\u00f3 a quedarme desnudo en la esquina de su habitaci\u00f3n, delante de mis hermanos mayores, que acababan de cenar con su padre, Andr\u00e9. (Cuando habl\u00e9 con\u00a0<em>People<\/em> en 2014 sobre esos episodios, Dylan lo calific\u00f3 de \u201ctraici\u00f3n\u201d y dijo que yo estaba \u201cmuerto\u201d para ella. M\u00e1s tarde, despreci\u00f3 en p\u00fablico los recuerdos de mi ni\u00f1ez diciendo que eran \u201cirrelevantes\u201d. Esto por parte de una mujer que ahora se presenta como \u201cdefensora de las v\u00edctimas del maltrato\u201d).<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20125\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Mia-Farrow-and-Andre-Previn.jpg\" alt=\"\" width=\"481\" height=\"300\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\">Mia Farrow y Andre Previn<\/span><\/p>\n<p>&nbsp;<\/p>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Plantar cara no era una opci\u00f3n viable. Un d\u00eda de verano, Mia me acus\u00f3 de dejar cerradas las cortinas de la sala donde ve\u00edamos la tele. Las hab\u00edan echado el d\u00eda anterior, cuando Dylan y Satchel hab\u00edan visto una pel\u00edcula. Insisti\u00f3 en que yo las hab\u00eda cerrado y las hab\u00eda dejado as\u00ed. Su amiga Casey hab\u00eda ido a verla y estaban en la cocina, mi madre insisti\u00f3 en que yo las hab\u00eda cerrado. En ese momento, yo no lo aguantaba m\u00e1s y perd\u00ed los nervios; grit\u00e9: \u201c\u00a1Est\u00e1s mintiendo!\u201d. Me mir\u00f3 con aspereza y me llev\u00f3 al ba\u00f1o que hab\u00eda junto al sal\u00f3n. Empez\u00f3 a pegarme de forma incontrolable por todo el cuerpo. Me abofete\u00f3, me empuj\u00f3 y me golpe\u00f3 en el pecho, gritando: \u201cC\u00f3mo puedes llamarme mentirosa delante de mi amiga. T\u00fa eres el mentiroso patol\u00f3gico\u201d. Me sent\u00eda derrotado, desinflado, apaleado y abatido. Mia me hab\u00eda quitado la voz y mi sentido de qui\u00e9n era. Estaba claro que no tolerar\u00eda que me apartara un poco de su realidad bien dise\u00f1ada. Fue una educaci\u00f3n que me hizo, de manera parad\u00f3jica, fieramente leal y obediente a ella y al mismo tiempo profundamente temeroso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En pocas palabras, no era un hogar feliz o sano. Lo que nos devuelve al 4 de agosto de 1992.En Twitter, hay desconocidos que me preguntan: \u201cNo estabas ah\u00ed para ver el abuso, \u00bfc\u00f3mo sabes que no sucedi\u00f3?\u201d Pero \u00bfc\u00f3mo podr\u00eda nadie ver un abuso si no ocurri\u00f3 nunca?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Como \u201chombre de la casa\u201d aquel d\u00eda, hab\u00eda prometido estar atento por si hab\u00eda alg\u00fan problema, y es justo lo que hice. Recuerdo d\u00f3nde se sentaba Woody en la sala de la tele, y puedo ver d\u00f3nde estaban Dylan y Satchel. No es que todo el mundo se quedara pegado en el mismo sitio, pero me esforc\u00e9 en fijarme d\u00f3nde iba cada uno. Recuerdo que Woody sali\u00f3 del sal\u00f3n alg\u00fan momento, pero nunca con Dylan. Iba a otra habitaci\u00f3n para hacer una llamada, leer el peri\u00f3dico, ir al ba\u00f1o o salir para tomar un poco de aire y caminar en torno al estanque que hab\u00eda en la propiedad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Hab\u00eda cinco ni\u00f1os y tres adultas en la casa, a las que se les hab\u00eda dicho durante meses lo monstruoso que era Woody. Ninguno de nosotros habr\u00eda permitido que Dylan se marchara con Woody, incluso si lo hubiera intentando. La ni\u00f1era de Casey, Alison, dijo despu\u00e9s que entr\u00f3 en la sala de la televisi\u00f3n y vio a Woody arrodillado en el suelo con su cabeza en el regazo de Dylan, que estaba sentada en el sof\u00e1. \u00bfEn serio? \u00bfCon todos nosotros ah\u00ed? Y si hubiera presenciado eso, \u00bfpor qu\u00e9 no dijo algo inmediatamente a nuestra ni\u00f1era Kristi? (Tambi\u00e9n recuerdo que se discuti\u00f3 sobre si esto ocurri\u00f3 en las escaleras que iban a la habitaci\u00f3n de Mia. De nuevo, esto lo habr\u00eda visto cualquiera que entrara al sal\u00f3n, y asumiendo en primer lugar que Woody consigui\u00f3 marcharse con Dylan). El relato ten\u00eda que cambiarse ya que el \u00fanico lugar donde se podr\u00eda cometer cualquier acto de depravaci\u00f3n en privado tendr\u00eda que haber sido la habitaci\u00f3n peque\u00f1a abuhardillada junto al dormitorio de mi madre en el piso de arriba. El \u00e1tico se convirti\u00f3 por defecto en la escena del supuesto abuso.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">En su famosa carta abierta de 2014 en\u00a0<em>The New York Times<\/em>, la Dylan adulta de pronto parec\u00eda recordar cada momento del supuesto abuso, escribiendo \u201cMe dijo que me tumbara boca abajo y jugara con el tren el\u00e9ctrico de mi hermano. Entonces abus\u00f3 sexualmente de mi. Me habl\u00f3 mientras lo hac\u00eda, susurrando que era una buena chica, que era nuestro secreto, prometi\u00e9ndome que ir\u00edamos a Par\u00eds y ser\u00eda una estrella en sus pel\u00edculas. Recuerdo mirar fijamente el tren de juguete, centr\u00e1ndome en c\u00f3mo daba vueltas por el \u00e1tico. A d\u00eda de hoy, me cuesta mirar trenes el\u00e9ctricos.\u201d<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Es un relato preciso y cautivador, pero tiene un principal problema: no hab\u00eda ning\u00fan tren el\u00e9ctrico. De hecho, no hab\u00eda manera de que los ni\u00f1os pudieran jugar ah\u00ed arriba, aunque hubi\u00e9ramos querido. Era una buhardilla inacabada, bajo un tejado a dos aguas, con clavos a la vista y tarimas, nubes de aislamiento de fibra de vidrio, lleno de trampas para ratones y excrementos y bolas de naftalina, y repleto de ba\u00fales llenos de ropa usada y el vestuario viejo de mi madre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La idea de que ese espacio pudiera haber albergado un tren el\u00e9ctrico operativo, que daba vueltas alrededor del \u00e1tico, es rid\u00edcula. Uno de mis hermanos ten\u00eda un tren el\u00e9ctrico, pero estaba en la habitaci\u00f3n de los ni\u00f1os, un garaje reconvertido en la primera planta. (\u00bfQuiz\u00e1 sea este el tren el\u00e9ctrico que mi hermana cree recordar?). Ahora, cada vez que oigo a Dylan hacer una declaraci\u00f3n p\u00fablica sobre lo que supuestamente le ocurri\u00f3 ese d\u00eda cuando apenas ten\u00eda siete a\u00f1os, solo puedo pensar en ese tren el\u00e9ctrico imaginario, que nunca mencion\u00f3 en la investigaci\u00f3n original o la sesi\u00f3n por la custodia. \u00bfAlguien sugiri\u00f3 a la Dylan adulta que ese detalle espec\u00edfico har\u00eda su historia m\u00e1s cre\u00edble? \u00bfO piensa realmente que recuerda ese tren \u201cdando vueltas alrededor del \u00e1tico\u201d del mismo modo que recuerda que Woody Allen le promet\u00eda al o\u00eddo viajes a Par\u00eds y el estrellato (una oferta un poco extra\u00f1a que hacerle a una ni\u00f1a de siete a\u00f1os, en vez de un juguete nuevo o una mu\u00f1eca)? \u00bfY todo esto ocurri\u00f3 supuestamente mientras aquellos que prometimos no perder de vista a Woody est\u00e1bamos en la planta baja, aparentemente ajenos a lo que estaba ocurriendo justo encima de nuestras cabezas?<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20127 size-mh-magazine-content\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Woody-Allen-sleeper-678x381.jpg\" alt=\"\" width=\"678\" height=\"381\" \/><\/p>\n<p>&nbsp;<\/p>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Al final de la tarde, mi madre volvi\u00f3 con Casey y sus adoptados m\u00e1s nuevos, Tam y el beb\u00e9 Isaiah. No hubo quejas de las ni\u00f1eras, y nada raro en el comportamiento de Dylan. De hecho, Woody y Mia salieron a cenar esa noche. Despu\u00e9s de la cena, volvieron a Frog Hollow y Woody se qued\u00f3 a dormir en una habitaci\u00f3n de la planta baja, y no hubo, aparentemente, ning\u00fan comportamiento anormal por parte de Dylan, y tampoco hubo ninguna queja de los adultos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">La ma\u00f1ana siguiente, Woody segu\u00eda en la casa. Antes de irse, deambul\u00e9 brevemente por el sal\u00f3n y vi a Dylan y Satchel sentados con \u00e9l en el suelo, apoyados en la pared frente al ventanal. Los ni\u00f1os ten\u00edan un cat\u00e1logo de una tienda de juguetes y estaban marcando los juguetes que quer\u00edan que les trajera en la pr\u00f3xima visita. Era una atm\u00f3sfera alegre y de juego, lo que chirr\u00eda con lo que Mia supuestamente dijo que ocurri\u00f3 un d\u00eda antes. Muchos a\u00f1os despu\u00e9s, mencion\u00e9 a Woody lo que recordaba, y dijo que \u00e9l tambi\u00e9n lo recordaba v\u00edvidamente: me dijo que les hab\u00eda dicho a Satchel y Dylan que marcaran uno o dos juguetes cada uno, pero, se re\u00eda, consiguieron marcar pr\u00e1cticamente todos los juguetes del cat\u00e1logo. Recuerda volver a la ciudad con el cat\u00e1logo, con la intenci\u00f3n de comprar algunos de los art\u00edculos que hab\u00edan seleccionado. Me dijo que acab\u00f3 conserv\u00e1ndolo durante a\u00f1os, sin saber si ver\u00eda a su hija nunca m\u00e1s.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Curiosamente, fue despu\u00e9s de que Woody volviera a la ciudad cuando Mia recibi\u00f3 una llamada de tel\u00e9fono que cambiar\u00eda nuestras vidas para siempre. Era de su amiga Casey, que le avis\u00f3 de que su ni\u00f1era Alison hab\u00eda visto a Woody supuestamente colocando su cabeza en el regazo de Dylan, en el sof\u00e1 de la sala de la tele.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Cuando Monica, nuestra ni\u00f1era de siempre que no estaba ese d\u00eda, volvi\u00f3 a trabajar al d\u00eda siguiente, le confes\u00e9 que pensaba que la historia era inventada. Monica, que llevaba con nosotros seis a\u00f1os, dimitir\u00eda unos meses despu\u00e9s. Dijo que Mia la hab\u00eda presionado para que se pusiera de su lado y apoyara la acusaci\u00f3n. Fue quien despu\u00e9s testific\u00f3 y dijo que vio a Mia grabando a Dylan describiendo c\u00f3mo Woody supuestamente la hab\u00eda tocado en el \u00e1tico; dijo que Mia estuvo dos o tres d\u00edas haciendo la grabaci\u00f3n. En su testimonio dijo: \u201crecuerdo a la se\u00f1ora Farrow diciendo a Dylan en ese momento, \u2018Dylan, \u00bfqu\u00e9 hizo pap\u00e1\u2026? \u00bfY qu\u00e9 hizo despu\u00e9s? Dylan no parec\u00eda interesada, y la se\u00f1ora Farrow paraba un rato y luego continuaba.\u201d Puedo dar fe de esto, ya que fui testigo de este proceso yo mismo. Cuando otro de los terapeutas de Dylan, la doctora Nancy Schultz, critic\u00f3 la creaci\u00f3n del v\u00eddeo, y cuestion\u00f3 la legitimidad del contenido, tambi\u00e9n fue despedida inmediatamente por Mia. (Mi madre, para quien la \u2018lealtad\u2019 era enormemente importante, tambi\u00e9n despidi\u00f3 a un cuidador de mucho tiempo, Mavis, alegando que estaba haciendo declaraciones contra ella.)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Durante la audiencia de la custodia, mi madre insist\u00eda en que necesit\u00e1bamos estar juntos como familia. Asustado y derrotado, yo tambi\u00e9n jugu\u00e9 mi parte. Incluso escrib\u00ed una carta condenando a Woody, donde dec\u00eda que hab\u00eda hecho algo horrible e imperdonable, y que hab\u00eda roto mis sue\u00f1os. Incluso le\u00ed la carta a los medios de comunicaci\u00f3n que estaban normalmente reunidos a la entrada de la casa, sabiendo que al hacerlo iba a ganar la aprobaci\u00f3n de mi madre. Esa denuncia p\u00fablica de mi padre sigue siendo uno de los mayores arrepentimientos de mi vida.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">M\u00e1s adelante ese a\u00f1o, recuerdo muchas reuniones con abogados y una evaluaci\u00f3n a la que fui en New Jersey. Soy vergonzoso por naturaleza y permanec\u00ed callado hasta que al final sent\u00ed que necesitaba pronunciarme. Le dije a mi evaluador que me sent\u00eda atrapado entre mis padres. Despu\u00e9s, volv\u00ed al colegio y mi madre me llam\u00f3 gritando. \u201c\u00bfTe das cuenta de lo que has hecho? \u00a1Has destruido mi caso! Tienes que llamar a tu abogado y decirle que retiras lo dicho, dile que te retractas y que quite tus declaraciones de la grabaci\u00f3n.\u201d Sent\u00ed que se me revolv\u00eda el est\u00f3mago. Cuando luego habl\u00e9 con el abogado, repet\u00ed las palabras tal cual: \u201cRetiro lo que dije; me retracto y quiero que quite mis declaraciones de la grabaci\u00f3n.\u201d De nuevo se cumpl\u00eda el patr\u00f3n: mi madre me forz\u00f3 a seguir su guion para probar mi lealtad.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Aunque todav\u00eda nos daba lecciones sobre \u201cestar juntos como una familia\u201d, al principio de mi segundo a\u00f1o de instituto, mi madre me envi\u00f3 contra mis deseos a un internado en Connecticut. Le dije que quer\u00eda quedarme en Nueva York; le dio igual. Ya no era de utilidad para el drama familiar. Hab\u00eda hecho mi declaraci\u00f3n contra mi padre, mi trabajo estaba hecho, y ahora me echaba.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Por entonces, por supuesto, no sab\u00eda nada de la investigaci\u00f3n criminal de seis meses dirigida por la Cl\u00ednica para los abusos sexuales de ni\u00f1os, del hospital de Yale\/New Haven, ordenada por la polic\u00eda estatal de Connecticut. Pero como las alegaciones se renovaron hace unos pocos a\u00f1os, he visto los resultados de esa investigaci\u00f3n. Conclu\u00eda espec\u00edficamente que \u201cDylan no fue abusada por el se\u00f1or Allen\u201d, que sus declaraciones ten\u00edan una \u201cnaturaleza ensayada\u201d y que fueron \u201cprobablemente fomentadas o influidas por su madre\u201d. Estas conclusiones encajan perfectamente con la experiencia de mi infancia: preparaci\u00f3n, influencia, ensayo, son tres palabras que resumen exactamente c\u00f3mo mi madre intent\u00f3 criarnos. S\u00e9 que Dylan se ha referido recientemente a esta teor\u00eda del lavado de cerebro como una \u201cmanipulaci\u00f3n\u201d de nuestro padre, pero no fue nada de eso. Esta no fue solo la conclusi\u00f3n a la que lleg\u00f3 una investigaci\u00f3n estatal, era la vida real en nuestro hogar.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Esa investigaci\u00f3n puso fin a cualquier posibilidad de cargos criminales contra mi padre. Una segunda investigaci\u00f3n de 14 meses, por el departamento de servicios sociales del estado se Nueva York, lleg\u00f3 a la misma conclusi\u00f3n que la de Yale\/New Haven: \u201cNo encontramos evidencias cre\u00edbles de que [Dylan Farrow] ha sido abusada o maltratada.\u201d Sin embargo, cuando un juez dio la custodia de Satchel y Dylan a Mia, yo ten\u00eda 15 a\u00f1os y eleg\u00ed el camino de la menor resistencia, y me qued\u00e9 con mi madre.<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-20126 size-mh-magazine-content\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2019\/07\/Dylan-Farrow-y-Woody-Allen-678x381.jpg\" alt=\"\" width=\"678\" height=\"381\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\">Dylan Farrow y Woody Allen<\/span><\/p>\n<p>&nbsp;<\/p>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Poco despu\u00e9s de graduarme de mi m\u00e1ster a los veinticinco a\u00f1os, sent\u00ed que quer\u00eda contactar con Woody, y se lo dije a Mia. Nunca olvidar\u00e9 lo feliz que me sent\u00ed cuando recib\u00ed un email suyo diciendo que me apoyar\u00eda, y que comprend\u00eda mi necesidad de tener una figura paternal. Esa felicidad dur\u00f3 poco. Menos de 24 horas despu\u00e9s cambi\u00f3 de opini\u00f3n y me escribi\u00f3 dici\u00e9ndome que me prohib\u00eda contactar con \u201cese monstruo\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Varios a\u00f1os despu\u00e9s, me fui separando de mi madre, pero he necesitado a\u00f1os de autorreflexi\u00f3n, ayuda profesional y apoyo de quienes quiero (y quienes me quieren de vuelta) para apreciar la triste verdad de mi infancia y lo que mi madre nos hizo a m\u00ed y a mis hermanos. Estoy agradecido de haber podido despertar y haber visto la verdad de lo que nos ocurri\u00f3, pero a la vez estoy decepcionado de haber tardado tanto en llegar aqu\u00ed.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Sin embargo, mi padre sigue enfrent\u00e1ndose una y otra vez a oleadas de ataques constantes e injustos de mi madre y sus suplentes, que cuestionan por qu\u00e9 se le ha perdonado todo estos a\u00f1os. Pero a Woody no se le ha perdonado todo. M\u00e1s bien lo contrario. La acusaci\u00f3n de Mia fue investigada completamente por dos agencias diferentes y nunca se presentaron cargos. Mia alcanz\u00f3 el final del camino legal despu\u00e9s de que se comprobara que el abuso nunca ocurri\u00f3. Pero el juicio medi\u00e1tico prospera gracias a la falta de memoria a largo plazo, y Twitter no necesita ni conocimiento ni restricciones.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A todos aquellos que est\u00e1is convencidos de la culpabilidad de mi padre, os pido que consider\u00e9is esto: en esta \u00e9poca de #MeToo, cuando tantos pesos pesados del cine se enfrentan a decenas de acusaciones, mi padre solo ha sido acusado de mal comportamiento una vez, por una expareja enfurecida en mitad de unas negociaciones beligerantes por una custodia. A lo largo de 60 a\u00f1os bajo el foco, ninguna otra persona ha comparecido para acusarlo siquiera de comportarse mal en una cita, o actuar inapropiadamente en cualquier situaci\u00f3n profesional, y menos a\u00fan de abusar de un ni\u00f1o. Como soy un profesional formado, s\u00e9 que la pederastia es una enfermedad compulsiva y una desviaci\u00f3n que demanda repetici\u00f3n. Dylan hab\u00eda estado sola con Woody en su apartamento en numerosas ocasiones a lo largo de los a\u00f1os sin que hubiera una pista de comportamiento inapropiado, y sin embargo hay quienes te hacen creer que a los 56 a\u00f1os, de pronto decidi\u00f3 convertirse en un pederasta en una casa llena de gente hostil a la que se le hab\u00eda pedido que lo vigile como un \u00e1guila.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A los actores que han trabajado con mi padre y han expresado arrepentimiento al hacerlo: os hab\u00e9is unido r\u00e1pidamente al coro de condena en base a una acusaci\u00f3n desacreditada por miedo a no estar en el lado \u201ccorrecto\u201d de un gran movimiento social. Pero en vez de aceptar el relato\u00a0de la turba de Twitter, que repite sin pensar una historia investigada y desacreditada hace 25 a\u00f1os, por favor considerad lo que tengo que decir. Despu\u00e9s de todo, estuve ah\u00ed -en la casa, en la habitaci\u00f3n- y conozco tanto a mi madre como a mi padre y lo que cada uno es capaz de hacer mucho mejor que vosotros.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">A mi hermana Dylan: como t\u00fa, creo en el poder de hablar p\u00fablicamente. He roto mi silencio sobre el abuso infligido por nuestra madre. Mi curaci\u00f3n comenz\u00f3 solo despu\u00e9s de alejarme de ella. Y lo que te ha hecho a ti es insoportable. Te deseo paz, y la sabidur\u00eda para entender que dedicar tu vida a ayudar a nuestra madre a destruir la reputaci\u00f3n de nuestro padre no creo que te permita pasar p\u00e1gina de manera definitiva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14pt;\">Finalmente, a mi madre. Una cosa que dec\u00edas que apreciabas de m\u00ed era mi habilidad para escuchar. Te escuch\u00e9 durante a\u00f1os y consider\u00e9 tu verdad por encima de las dem\u00e1s. Una vez me dijiste: \u201cNo es sano aferrarse al odio\u201d. Y sin embargo aqu\u00ed estamos, 26 a\u00f1os despu\u00e9s. Imagino que tu siguiente paso ser\u00e1 lanzar una campa\u00f1a para desacreditarme por hablar en p\u00fablico. S\u00e9 que es lo que toca. Y es una carga que estoy dispuesto a soportar. Pero despu\u00e9s de todo este tiempo, ya basta. Ambos sabemos la verdad. Es hora de que acabe este castigo.<\/span><\/p>\n<\/div>\n<section class=\"col-md-9 post\">\n<div class=\"timeparent\">\n<div id=\"block-views-block-teaser-author-in-article-block-author-in-article\" class=\"views-element-container\">\n<div>\n<div class=\"js-view-dom-id-99285894516385e1a7fe8442ea2b7021c65c465c3018a6bc32dc4978b0620c8c\">\n<div class=\"views-row\">\n<div class=\"views-field views-field-field-letraslibres-author\">\n<div class=\"field-content\">\n<section class=\"article-author-footer\">\n<div class=\"media\">\n<div class=\"media-body\">\n<div>\u00a0<\/div>\n<div><span style=\"font-size: 14pt;\"><em>* Moses Farrow es psiquiatra.<\/em><\/span><\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<aside class=\"col-md-3 sidebar\">\n<div>\n<div id=\"block-views-block-pdf-de-articulo-sidebar-block-block-1\" class=\"views-element-container\">\n<div>\n<div class=\"js-view-dom-id-1ac2dead306820feee0c199bbcea0f764a9f8f55f770f8c1689f18e7b06f3560\">\n<div class=\"views-row\">\n<div class=\"views-field views-field-nothing\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/aside>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><em>Traducci\u00f3n de Daniel Gasc\u00f3n y Ricardo Dudda.<\/em><\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"font-size: 14pt;\"><em>Con el permiso del autor.\u00a0Publicado\u00a0<a href=\"http:\/\/mosesfarrow.blogspot.com\/2018\/05\/a-son-speaks-out-by-moses-farrow.html\" target=\"_blank\" rel=\"noopener\">originalmente<\/a>\u00a0en el blog <a href=\"http:\/\/mosesfarrow.blogspot.com\" target=\"_blank\" rel=\"noopener\">mosesfarrow.blogspot.com<\/a><\/em><\/span><\/p>\n<\/div>\n<div role=\"region\" aria-labelledby=\"at-d3d6f0e9-0c2e-4392-86c2-ee42b597527a\">\u00a0<\/div>\n<p><a href=\"https:\/\/puntocritico.com\/ausajpuntocritico\/author\/punto-critico\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9528\" src=\"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-content\/uploads\/2018\/03\/Mosca_Punto_Cr\u00edtico_40.png\" alt=\"\" width=\"70\" height=\"70\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Cr\u00e9dito y cinismo: el valor social de la verdad Hemos transformado el debate p\u00fablico en una enfermedad autoinmune que, en lugar de proteger y fortalecer el sistema, lo ataca.\u00a0 \u00a0 Por Elena Alfaro \u00a0 \u00a0 <a class=\"mh-excerpt-more\" href=\"https:\/\/puntocritico.com\/ausajpuntocritico\/2019\/07\/15\/el-caso-woody-allen-un-hijo-toma-la-palabra-por-moses-farrow\/\" title=\"\u00abEl caso Woody Allen: Un hijo toma la palabra\u00bb, por Moses Farrow\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":3,"featured_media":20158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-20115","post","type-post","status-publish","format-standard","has-post-thumbnail","category-miscelanea"],"acf":[],"_links":{"self":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/posts\/20115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/comments?post=20115"}],"version-history":[{"count":0,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/posts\/20115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/media\/20158"}],"wp:attachment":[{"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/media?parent=20115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/categories?post=20115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puntocritico.com\/ausajpuntocritico\/wp-json\/wp\/v2\/tags?post=20115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}